{"id":23273,"date":"2025-01-11T16:32:27","date_gmt":"2025-01-11T16:32:27","guid":{"rendered":"https:\/\/welcomealghero.com\/restaurant\/ok-pizza-evolution-ristorante-pizzeria\/"},"modified":"2025-01-11T16:32:27","modified_gmt":"2025-01-11T16:32:27","slug":"ok-pizza-evolution-ristorante-pizzeria","status":"publish","type":"restaurant","link":"https:\/\/welcomealghero.com\/de\/restaurant\/ok-pizza-evolution-ristorante-pizzeria\/","title":{"rendered":"Ok Pizza Evolution - Ristorante Pizzeria"},"content":{"rendered":"<p>&nbsp;<\/p>\n<div>\n<h2 class=\"font-weight-bold mb-3 line-height-1 color-primary-darkest\">Um<\/h2>\n<p>Ok Pizza Evolution ~ Dieses Pizzarestaurant befindet sich in Alghero auf Sardinien und bietet Mitnahme oder Lieferung an. Das Restaurant hat Platz f\u00fcr bis zu 40 G\u00e4ste und bietet Tischbedienung. Das Restaurant akzeptiert Kreditkartenzahlungen und serviert Alkohol.<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<div class=\"flex rounded-16 p-4 bg-indigo-lightest\">\n<h4 class=\"font-weight-bold pb-2\" style=\"color: #2c365d;\">Warum Sie hingehen sollten...<\/h4>\n<div><\/div>\n<ul>\n<li class=\"d-flex align-items-center\">Genie\u00dfen Sie Gourmet-Pizzen mit knuspriger Kruste<\/li>\n<li class=\"d-flex align-items-center\">Erleben Sie Top-Top-Service durch freundliches Personal<\/li>\n<li class=\"d-flex align-items-center\">Angebote wie kostenlose Desserts oder kreative Pizzapr\u00e4sentationen<\/li>\n<\/ul>\n<\/div>\n<p>Viale della Resistenza, 8, 07041 Alghero SS, Italien<br \/>\n<a href=\"https:\/\/www.okpizzaevolution.it\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.okpizzaevolution.it\/<\/a><br \/>\n+39 079 973 3022<\/p>","protected":false},"featured_media":23316,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"iawp_total_views":12},"restaurant-tag":[4],"class_list":["post-23273","restaurant","type-restaurant","status-publish","has-post-thumbnail","hentry","restaurant-tag-pizza"],"acf":[],"_links":{"self":[{"href":"https:\/\/welcomealghero.com\/de\/wp-json\/wp\/v2\/restaurant\/23273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/welcomealghero.com\/de\/wp-json\/wp\/v2\/restaurant"}],"about":[{"href":"https:\/\/welcomealghero.com\/de\/wp-json\/wp\/v2\/types\/restaurant"}],"replies":[{"embeddable":true,"href":"https:\/\/welcomealghero.com\/de\/wp-json\/wp\/v2\/comments?post=23273"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/welcomealghero.com\/de\/wp-json\/wp\/v2\/media\/23316"}],"wp:attachment":[{"href":"https:\/\/welcomealghero.com\/de\/wp-json\/wp\/v2\/media?parent=23273"}],"wp:term":[{"taxonomy":"restaurant-tag","embeddable":true,"href":"https:\/\/welcomealghero.com\/de\/wp-json\/wp\/v2\/restaurant-tag?post=23273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}