{"id":23583,"date":"2025-01-31T14:52:07","date_gmt":"2025-01-31T14:52:07","guid":{"rendered":"https:\/\/welcomealghero.com\/?post_type=thing-to-do&amp;p=23583"},"modified":"2025-01-31T14:52:07","modified_gmt":"2025-01-31T14:52:07","slug":"casa-de-ferrera-palazzo-d-albis","status":"publish","type":"thing-to-do","link":"https:\/\/welcomealghero.com\/de\/thing-to-do\/casa-de-ferrera-palazzo-d-albis\/","title":{"rendered":"Casa De Ferrera \u2013 Palazzo d\u2019 Alb\u00ecs"},"content":{"rendered":"<p>Die heutige Piazza Civica wurde Mitte des 15. Jahrhunderts innerhalb der historischen Stadtmauern erbaut und geh\u00f6rte urspr\u00fcnglich der Familie De Ferrera, wohlhabenden katalanischen Kaufleuten. Nach ihren sp\u00e4teren Besitzern wird sie auch als Casa d'Albis und Palazzo d'Arcayne bezeichnet und diente als offizielle Residenz des Milit\u00e4rgouverneurs der Stadt. Am bekanntesten ist er jedoch f\u00fcr die Beherbergung von Kaiser Karl V. w\u00e4hrend seines zweit\u00e4gigen Besuchs in Alghero im Oktober 1541, der Teil seiner Expedition gegen Algier war.<\/p>\n<p>Das im gotischen Baustil errichtete Geb\u00e4ude besteht aus drei Stockwerken, die durch eine Reihe von Gurtb\u00f6gen voneinander getrennt sind, wobei der zweite und oberste Gurtbogen noch heute sichtbar sind. Im Jahr 1960 wurde dieses historische Geb\u00e4ude in eine Eigentumswohnung umgewandelt.<\/p>","protected":false},"featured_media":23765,"template":"","meta":{"_acf_changed":false,"iawp_total_views":12},"class_list":["post-23583","thing-to-do","type-thing-to-do","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/welcomealghero.com\/de\/wp-json\/wp\/v2\/thing-to-do\/23583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/welcomealghero.com\/de\/wp-json\/wp\/v2\/thing-to-do"}],"about":[{"href":"https:\/\/welcomealghero.com\/de\/wp-json\/wp\/v2\/types\/thing-to-do"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/welcomealghero.com\/de\/wp-json\/wp\/v2\/media\/23765"}],"wp:attachment":[{"href":"https:\/\/welcomealghero.com\/de\/wp-json\/wp\/v2\/media?parent=23583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}