{"id":22895,"date":"2025-01-14T11:42:39","date_gmt":"2025-01-14T11:42:39","guid":{"rendered":"https:\/\/welcomealghero.com\/?post_type=hotels&amp;p=22895"},"modified":"2025-01-14T11:42:39","modified_gmt":"2025-01-14T11:42:39","slug":"blue-wave","status":"publish","type":"hotels","link":"https:\/\/welcomealghero.com\/es\/hotels\/blue-wave\/","title":{"rendered":"Ola azul"},"content":{"rendered":"<h1 class=\"KOaa-hotel-name\">Ola azul<\/h1>\n<div class=\"nWFW-address\"><strong>Via Palmiro Togliatti 15, 07041 Alghero, Cerde\u00f1a, Italia<\/strong><\/div>\n<div><\/div>\n<div><span class=\"wordai-block rewrite-block enable-highlight\" data-id=\"1\">El B&amp;B Blue Wave est\u00e1 a s\u00f3lo 10 minutos a pie del centro de Alghero y de la playa de Calabona.<\/span>\u00a0<span class=\"wordai-block rewrite-block enable-highlight\" data-id=\"2\">El B&amp;B ofrece habitaciones con aire acondicionado y un desayuno italiano.<\/span>\u00a0<span class=\"wordai-block rewrite-block enable-highlight\" data-id=\"3\">Las habitaciones del Blue Wave disponen de ba\u00f1o privado con art\u00edculos de aseo gratuitos y secador de pelo.<\/span>\u00a0<span class=\"wordai-block rewrite-block enable-highlight\" data-id=\"4\">Todas las ma\u00f1anas se sirve un desayuno dulce de autoservicio en la habitaci\u00f3n.<\/span>\u00a0<span class=\"wordai-block rewrite-block enable-highlight\" data-id=\"5\">En la zona com\u00fan hay una nevera.<\/span>\u00a0<span class=\"wordai-block rewrite-block enable-highlight\" data-id=\"6\">A dos minutos a pie del hotel hay una parada de autob\u00fas que conecta con las playas de la zona.<\/span>\u00a0<span class=\"wordai-block rewrite-block enable-highlight\" data-id=\"7\">El aparcamiento est\u00e1 disponible in situ.<\/span><\/div>\n<div><\/div>\n<p><span style=\"font-weight: 800;\">Valoraci\u00f3n: <\/span><span style=\"font-size: 16px;\">8.8<\/span><\/p>\n<div class=\"hotel_checklist\">\n<section id=\"\" class=\"Vdvb Vdvb-mod-size-desktop-large-mobile-standard Vdvb-mod-separator Vdvb-mod-color-default\">\n<div class=\"Vdvb-header-container\" data-testid=\"header\">\n<h2 class=\"Vdvb-title\">Servicios en Blue Wave<\/h2>\n<\/div>\n<ul class=\"kml-row\">\n<li class=\"kml-col-12-12 kml-col-6-12-m\"><span class=\"t8Xi-amenity-name\">Wi-Fi gratuito<\/span><\/li>\n<li class=\"kml-col-12-12 kml-col-6-12-m\"><span class=\"t8Xi-amenity-name\">Art\u00edculos de aseo gratuitos<\/span><\/li>\n<li class=\"kml-col-12-12 kml-col-6-12-m\"><span class=\"t8Xi-amenity-name\">Aparcamiento<\/span><\/li>\n<li class=\"kml-col-12-12 kml-col-6-12-m\"><span class=\"t8Xi-amenity-name\">Secador de pelo<\/span><\/li>\n<li class=\"kml-col-12-12 kml-col-6-12-m\"><span class=\"t8Xi-amenity-name\">Salida expr\u00e9s<\/span><\/li>\n<li class=\"kml-col-12-12 kml-col-6-12-m\"><span class=\"t8Xi-amenity-name\">Recepci\u00f3n 24 horas<\/span><\/li>\n<li class=\"kml-col-12-12 kml-col-6-12-m\"><span class=\"t8Xi-amenity-name\">Acceso a la playa<\/span><\/li>\n<li class=\"kml-col-12-12 kml-col-6-12-m\"><span class=\"t8Xi-amenity-name\">Frigor\u00edfico<\/span><\/li>\n<li class=\"kml-col-12-12 kml-col-6-12-m\"><span class=\"t8Xi-amenity-name\">Aire acondicionado<\/span><\/li>\n<li class=\"kml-col-12-12 kml-col-6-12-m\"><span class=\"t8Xi-amenity-name\">Habitaciones para no fumadores<\/span><\/li>\n<\/ul>\n<div>\n<div class=\"kml-row DbSA-categories-container\">\n<div class=\"kml-col-12-12 kml-col-6-12-m\">\n<p class=\"BxLB-category-name\">Conceptos b\u00e1sicos<\/p>\n<ul>\n<li class=\"BxLB-amenity\"><span class=\"BxLB-amenity-name\">Ventilador<\/span><\/li>\n<li class=\"BxLB-amenity\"><span class=\"BxLB-amenity-name\">Wi-Fi gratuito<\/span><\/li>\n<li class=\"BxLB-amenity\"><span class=\"BxLB-amenity-name\">Aire acondicionado<\/span><\/li>\n<li class=\"BxLB-amenity\"><span class=\"BxLB-amenity-name\">Art\u00edculos de aseo gratuitos<\/span><\/li>\n<\/ul>\n<\/div>\n<div class=\"kml-col-12-12 kml-col-6-12-m\">\n<p class=\"BxLB-category-name\">Comedor<\/p>\n<ul>\n<li class=\"BxLB-amenity\"><span class=\"BxLB-amenity-name\">Minibar<\/span><\/li>\n<li class=\"BxLB-amenity\"><span class=\"BxLB-amenity-name\">Frigor\u00edfico<\/span><\/li>\n<\/ul>\n<\/div>\n<div class=\"kml-col-12-12 kml-col-6-12-m\">\n<p class=\"BxLB-category-name\">Servicios y comodidades<\/p>\n<ul>\n<li class=\"BxLB-amenity\"><span class=\"BxLB-amenity-name\">Salida expr\u00e9s<\/span><\/li>\n<li class=\"BxLB-amenity\"><span class=\"BxLB-amenity-name\">Recepci\u00f3n 24 horas<\/span><\/li>\n<\/ul>\n<\/div>\n<div class=\"kml-col-12-12 kml-col-6-12-m\">\n<p class=\"BxLB-category-name\">Aparcamiento y transporte<\/p>\n<ul>\n<li class=\"BxLB-amenity\"><span class=\"BxLB-amenity-name\">Aparcamiento<\/span><\/li>\n<\/ul>\n<\/div>\n<div class=\"kml-col-12-12 kml-col-6-12-m\">\n<p class=\"BxLB-category-name\">Accesibilidad e idoneidad<\/p>\n<ul>\n<li class=\"BxLB-amenity\"><span class=\"BxLB-amenity-name\">Habitaciones para no fumadores<\/span><\/li>\n<\/ul>\n<\/div>\n<div class=\"kml-col-12-12 kml-col-6-12-m\">\n<p class=\"BxLB-category-name\">Cuarto de ba\u00f1o<\/p>\n<ul>\n<li class=\"BxLB-amenity\"><span class=\"BxLB-amenity-name\">Secador de pelo<\/span><\/li>\n<\/ul>\n<\/div>\n<div class=\"kml-col-12-12 kml-col-6-12-m\">\n<p class=\"BxLB-category-name\">Actividades<\/p>\n<ul>\n<li class=\"BxLB-amenity\"><span class=\"BxLB-amenity-name\">Acceso a la playa<\/span><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<div class=\"DbSA-button-wrapper\"><\/div>\n<\/div>\n<\/section>\n<\/div>\n<section id=\"\" class=\"Vdvb Vdvb-mod-size-desktop-large-mobile-standard Vdvb-mod-separator Vdvb-mod-color-default\">\n<div class=\"Vdvb-header-container\" data-testid=\"header\">\n<h2 class=\"Vdvb-title\">Pol\u00edticas<\/h2>\n<\/div>\n<table class=\"Q6C3-table\">\n<tbody class=\"kml-row\">\n<tr class=\"kml-col-6-12-m\">\n<th class=\"Q6C3-title-wrapper\">\n<h3 class=\"Q6C3-title\">Registro de entrada\/salida<\/h3>\n<\/th>\n<td class=\"Q6C3-description\">Entrada a partir de las 18.00 y salida antes de las 10.00.<\/td>\n<\/tr>\n<tr class=\"kml-col-6-12-m\">\n<th class=\"Q6C3-title-wrapper\">\n<h3 class=\"Q6C3-title\">Anulaci\u00f3n\/pago anticipado<\/h3>\n<\/th>\n<td class=\"Q6C3-description\">Las pol\u00edticas de cancelaci\u00f3n\/pago anticipado var\u00edan seg\u00fan el tipo de habitaci\u00f3n y el proveedor.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/section>","protected":false},"featured_media":22896,"template":"","meta":{"_acf_changed":false,"iawp_total_views":13},"hotel-tag":[],"class_list":["post-22895","hotels","type-hotels","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/welcomealghero.com\/es\/wp-json\/wp\/v2\/hotels\/22895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/welcomealghero.com\/es\/wp-json\/wp\/v2\/hotels"}],"about":[{"href":"https:\/\/welcomealghero.com\/es\/wp-json\/wp\/v2\/types\/hotels"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/welcomealghero.com\/es\/wp-json\/wp\/v2\/media\/22896"}],"wp:attachment":[{"href":"https:\/\/welcomealghero.com\/es\/wp-json\/wp\/v2\/media?parent=22895"}],"wp:term":[{"taxonomy":"hotel-tag","embeddable":true,"href":"https:\/\/welcomealghero.com\/es\/wp-json\/wp\/v2\/hotel-tag?post=22895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}