{"id":22899,"date":"2025-01-14T11:36:48","date_gmt":"2025-01-14T11:36:48","guid":{"rendered":"https:\/\/welcomealghero.com\/?post_type=hotels&amp;p=22899"},"modified":"2025-01-14T11:36:48","modified_gmt":"2025-01-14T11:36:48","slug":"butterfly-house-bb","status":"publish","type":"hotels","link":"https:\/\/welcomealghero.com\/es\/hotels\/butterfly-house-bb\/","title":{"rendered":"Casa de las Mariposas"},"content":{"rendered":"<h1 class=\"KOaa-hotel-name\">Casa de las Mariposas<\/h1>\n<div class=\"nWFW-address\"><strong>Localita Carrabuffas 38, 07041 Alghero, Cerde\u00f1a, Italia<\/strong><\/div>\n<p><span class=\"wordai-block rewrite-block enable-highlight\" data-id=\"1\">El Butterfly House, un bed and breakfast situado en el tranquilo centro de Alghero, est\u00e1 rodeado de vegetaci\u00f3n y ofrece alojamientos modernos con porches y hamacas.<\/span><\/p>\n<p><span class=\"wordai-block rewrite-block enable-highlight active\" data-id=\"2\">La habitaci\u00f3n con aire acondicionado presenta azulejos frescos y paredes en colores vivos. Tambi\u00e9n dispone de nevera, TV de pantalla plana y set de t\u00e9 y caf\u00e9.<\/span>\u00a0<span class=\"wordai-block rewrite-block enable-highlight\" data-id=\"3\">Se incluye un cuarto de ba\u00f1o privado con ducha.<\/span><\/p>\n<p><span class=\"wordai-block rewrite-block enable-highlight\" data-id=\"4\">El Butterfly House Bed &amp; Breakfast proporciona acceso gratuito a la cocina, que incluye nevera y cafetera.<\/span>\u00a0<span class=\"wordai-block rewrite-block enable-highlight\" data-id=\"5\">Recibir\u00e1 una cesta de desayuno dulce o salado cada ma\u00f1ana.<\/span>\u00a0<span class=\"wordai-block rewrite-block enable-highlight\" data-id=\"6\">La terraza compartida est\u00e1 equipada con sillas y mesas.<\/span><\/p>\n<p><span class=\"wordai-block rewrite-block enable-highlight\" data-id=\"7\">El aparcamiento es gratuito y el establecimiento est\u00e1 a s\u00f3lo 10 minutos en coche de la playa de Lido San Giovanni.<\/span>\u00a0<span class=\"wordai-block rewrite-block enable-highlight\" data-id=\"8\">Tendr\u00e1 que conducir usted mismo, ya que el transporte p\u00fablico no llega a la propiedad.<\/span><\/p>\n<div class=\"hotel_checklist\">\n<section id=\"\" class=\"Vdvb Vdvb-mod-size-desktop-large-mobile-standard Vdvb-mod-separator Vdvb-mod-color-default\">\n<div class=\"Vdvb-header-container\" data-testid=\"header\">\n<h2 class=\"Vdvb-title\">Servicios de Butterfly House B&amp;B<\/h2>\n<\/div>\n<ul class=\"kml-row\">\n<li class=\"kml-col-12-12 kml-col-6-12-m\"><span class=\"t8Xi-amenity-name\">Wi-Fi gratuito<\/span><\/li>\n<li class=\"kml-col-12-12 kml-col-6-12-m\"><span class=\"t8Xi-amenity-name\">Aire acondicionado<\/span><\/li>\n<li class=\"kml-col-12-12 kml-col-6-12-m\"><span class=\"t8Xi-amenity-name\">Transporte al aeropuerto<\/span><\/li>\n<li class=\"kml-col-12-12 kml-col-6-12-m\"><span class=\"t8Xi-amenity-name\">Secador de pelo<\/span><\/li>\n<li class=\"kml-col-12-12 kml-col-6-12-m\"><span class=\"t8Xi-amenity-name\">Salida expr\u00e9s<\/span><\/li>\n<li class=\"kml-col-12-12 kml-col-6-12-m\"><span class=\"t8Xi-amenity-name\">Microondas<\/span><\/li>\n<li class=\"kml-col-12-12 kml-col-6-12-m\"><span class=\"t8Xi-amenity-name\">Frigor\u00edfico<\/span><\/li>\n<li class=\"kml-col-12-12 kml-col-6-12-m\"><span class=\"t8Xi-amenity-name\">Habitaciones para no fumadores<\/span><\/li>\n<li class=\"kml-col-12-12 kml-col-6-12-m\"><span class=\"t8Xi-amenity-name\">Zona designada para fumadores<\/span><\/li>\n<li class=\"kml-col-12-12 kml-col-6-12-m\"><span class=\"t8Xi-amenity-name\">Almacenamiento disponible<\/span><\/li>\n<\/ul>\n<div>\n<div class=\"kml-row DbSA-categories-container\">\n<div class=\"kml-col-12-12 kml-col-6-12-m\">\n<p class=\"BxLB-category-name\">Accesibilidad e idoneidad<\/p>\n<ul>\n<li class=\"BxLB-amenity\"><span class=\"BxLB-amenity-name\">Habitaciones para no fumadores<\/span><\/li>\n<li class=\"BxLB-amenity\"><span class=\"BxLB-amenity-name\">Zona designada para fumadores<\/span><\/li>\n<\/ul>\n<\/div>\n<div class=\"kml-col-12-12 kml-col-6-12-m\">\n<p class=\"BxLB-category-name\">Comedor<\/p>\n<ul>\n<li class=\"BxLB-amenity\"><span class=\"BxLB-amenity-name\">Microondas<\/span><\/li>\n<li class=\"BxLB-amenity\"><span class=\"BxLB-amenity-name\">Frigor\u00edfico<\/span><\/li>\n<\/ul>\n<\/div>\n<div class=\"kml-col-12-12 kml-col-6-12-m\">\n<p class=\"BxLB-category-name\">Conceptos b\u00e1sicos<\/p>\n<ul>\n<li class=\"BxLB-amenity\"><span class=\"BxLB-amenity-name\">Wi-Fi gratuito<\/span><\/li>\n<li class=\"BxLB-amenity\"><span class=\"BxLB-amenity-name\">Aire acondicionado<\/span><\/li>\n<\/ul>\n<\/div>\n<div class=\"kml-col-12-12 kml-col-6-12-m\">\n<p class=\"BxLB-category-name\">Aparcamiento y transporte<\/p>\n<ul>\n<li class=\"BxLB-amenity\"><span class=\"BxLB-amenity-name\">Transporte al aeropuerto<\/span><\/li>\n<\/ul>\n<\/div>\n<div class=\"kml-col-12-12 kml-col-6-12-m\">\n<p class=\"BxLB-category-name\">Cuarto de ba\u00f1o<\/p>\n<ul>\n<li class=\"BxLB-amenity\"><span class=\"BxLB-amenity-name\">Secador de pelo<\/span><\/li>\n<\/ul>\n<\/div>\n<div class=\"kml-col-12-12 kml-col-6-12-m\">\n<p class=\"BxLB-category-name\">General<\/p>\n<ul>\n<li class=\"BxLB-amenity\"><span class=\"BxLB-amenity-name\">Almacenamiento disponible<\/span><\/li>\n<\/ul>\n<\/div>\n<div class=\"kml-col-12-12 kml-col-6-12-m\">\n<p class=\"BxLB-category-name\">Servicios y comodidades<\/p>\n<ul>\n<li class=\"BxLB-amenity\"><span class=\"BxLB-amenity-name\">Salida expr\u00e9s<\/span><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<section id=\"\" class=\"Vdvb Vdvb-mod-size-desktop-large-mobile-standard Vdvb-mod-separator Vdvb-mod-color-default\">\n<div class=\"Vdvb-header-container\" data-testid=\"header\">\n<h2 class=\"Vdvb-title\">Pol\u00edticas<\/h2>\n<\/div>\n<table class=\"Q6C3-table\">\n<tbody class=\"kml-row\">\n<tr class=\"kml-col-6-12-m\">\n<th class=\"Q6C3-title-wrapper\">\n<h3 class=\"Q6C3-title\">Registro de entrada\/salida<\/h3>\n<\/th>\n<td class=\"Q6C3-description\">Entrada a partir de las 12.00 y salida antes de las 11.00.<\/td>\n<\/tr>\n<tr class=\"kml-col-6-12-m\">\n<th class=\"Q6C3-title-wrapper\">\n<h3 class=\"Q6C3-title\">Anulaci\u00f3n\/pago anticipado<\/h3>\n<\/th>\n<td class=\"Q6C3-description\">Las pol\u00edticas de cancelaci\u00f3n\/pago anticipado var\u00edan seg\u00fan el tipo de habitaci\u00f3n y el proveedor.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/section>","protected":false},"featured_media":23338,"template":"","meta":{"_acf_changed":false,"iawp_total_views":11},"hotel-tag":[],"class_list":["post-22899","hotels","type-hotels","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/welcomealghero.com\/es\/wp-json\/wp\/v2\/hotels\/22899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/welcomealghero.com\/es\/wp-json\/wp\/v2\/hotels"}],"about":[{"href":"https:\/\/welcomealghero.com\/es\/wp-json\/wp\/v2\/types\/hotels"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/welcomealghero.com\/es\/wp-json\/wp\/v2\/media\/23338"}],"wp:attachment":[{"href":"https:\/\/welcomealghero.com\/es\/wp-json\/wp\/v2\/media?parent=22899"}],"wp:term":[{"taxonomy":"hotel-tag","embeddable":true,"href":"https:\/\/welcomealghero.com\/es\/wp-json\/wp\/v2\/hotel-tag?post=22899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}