{"id":23134,"date":"2025-01-09T22:03:04","date_gmt":"2025-01-09T22:03:04","guid":{"rendered":"https:\/\/welcomealghero.com\/restaurant\/al-vecchio-mulino\/"},"modified":"2026-08-06T08:04:06","modified_gmt":"2026-08-06T08:04:06","slug":"al-vecchio-mulino","status":"publish","type":"restaurant","link":"https:\/\/welcomealghero.com\/es\/restaurant\/al-vecchio-mulino\/","title":{"rendered":"Al Vecchio Mulino"},"content":{"rendered":"<p>&nbsp;<\/p>\n<div>\n<h2 class=\"font-weight-bold mb-3 line-height-1 color-primary-darkest\">Acerca de<\/h2>\n<p>Al Vecchio Mulino Es popular entre los lugare\u00f1os. Antiguo molino con atm\u00f3sfera de gruta, techos bajos abovedados y ambiente animado. El men\u00fa ofrece un excelente equilibrio entre carne y marisco, como pastas locales con embutidos, gambas fritas, pescado y pizzas frescas y crujientes.<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<div class=\"flex rounded-16 p-4 bg-indigo-lightest\">\n<div class=\"font-weight-bold pb-2\" style=\"color: #2c365d;\">Por qu\u00e9 debe ir<\/div>\n<div class=\"d-flex align-items-center\">Se pueden degustar culurgiones, fregola sarda y otras delicias de la cocina sarda.<\/div>\n<div class=\"d-flex align-items-center\">El personal es amable y ofrece un excelente servicio al cliente.<\/div>\n<div class=\"d-flex align-items-center\">Podr\u00e1 disfrutar de deliciosas pizzas al horno de piedra con cortezas crujientes y finas.<\/div>\n<\/div>\n<p><a href=\"https:\/\/www.google.com\/maps\/search\/?api=1&amp;query=Al+Vecchio+Mulino%2C+Via+Don+Deroma%2C+3%2C+07041+Alghero+SS%2C+Italy&amp;query_place_id=ChIJ302xguDx3BIR683asELAuwg\" target=\"_blank\" rel=\"noopener\">Via Don Deroma, 3, 07041 Alghero SS, Italia<\/a><br \/>\n<a class=\"text-nowrap\" href=\"https:\/\/wanderlog.com\/place\/details\/1160740\/tel:+39-079-977254\" target=\"_blank\" rel=\"noopener\">+39 079 977254<\/a><\/p>","protected":false},"featured_media":23135,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"iawp_total_views":73},"restaurant-tag":[4],"class_list":["post-23134","restaurant","type-restaurant","status-publish","has-post-thumbnail","hentry","restaurant-tag-pizza"],"acf":[],"_links":{"self":[{"href":"https:\/\/welcomealghero.com\/es\/wp-json\/wp\/v2\/restaurant\/23134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/welcomealghero.com\/es\/wp-json\/wp\/v2\/restaurant"}],"about":[{"href":"https:\/\/welcomealghero.com\/es\/wp-json\/wp\/v2\/types\/restaurant"}],"replies":[{"embeddable":true,"href":"https:\/\/welcomealghero.com\/es\/wp-json\/wp\/v2\/comments?post=23134"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/welcomealghero.com\/es\/wp-json\/wp\/v2\/media\/23135"}],"wp:attachment":[{"href":"https:\/\/welcomealghero.com\/es\/wp-json\/wp\/v2\/media?parent=23134"}],"wp:term":[{"taxonomy":"restaurant-tag","embeddable":true,"href":"https:\/\/welcomealghero.com\/es\/wp-json\/wp\/v2\/restaurant-tag?post=23134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}