{"id":23217,"date":"2025-01-10T13:10:40","date_gmt":"2025-01-10T13:10:40","guid":{"rendered":"https:\/\/welcomealghero.com\/restaurant\/gior-osteria-pizza-gourmet\/"},"modified":"2025-01-10T13:10:40","modified_gmt":"2025-01-10T13:10:40","slug":"gior-osteria-pizza-gourmet","status":"publish","type":"restaurant","link":"https:\/\/welcomealghero.com\/es\/restaurant\/gior-osteria-pizza-gourmet\/","title":{"rendered":"Gior Osteria Pizza Gourmet"},"content":{"rendered":"<p>&nbsp;<\/p>\n<div>\n<h2 class=\"font-weight-bold mb-3 line-height-1 color-primary-darkest\">Acerca de<\/h2>\n<p>Gior Osteria Pizza Gourmet Esta joya culinaria se encuentra a s\u00f3lo 0,2 millas de Alghero. El conocido restaurante sirve una deliciosa selecci\u00f3n de pizzas gourmet, elaboradas con los mejores ingredientes. Tambi\u00e9n ofrece creaciones \u00fanicas como pasta con pesto de pistacho. La comida es deliciosa y, a pesar de algunas cr\u00edticas negativas sobre la calidad del marisco, los visitantes se deshacen en elogios.<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<div class=\"flex rounded-16 p-4 bg-indigo-lightest\">\n<div class=\"font-weight-bold pb-2\" style=\"color: #2c365d;\">Debe visitar<\/div>\n<div class=\"d-flex align-items-center\">Disfrute de pizzas gourmet elaboradas con los mejores ingredientes<\/div>\n<div class=\"d-flex align-items-center\">Men\u00fas especiales como Pasta con Pistacho-Pesto<\/div>\n<div class=\"d-flex align-items-center\">Disfrute de deliciosos platos como at\u00fan y pulpo a la parrilla<\/div>\n<\/div>\n<p>Largo S. Francesco, 8, 07041 Alghero SS, Italia<br \/>\n+39 079 914 6568<\/p>","protected":false},"featured_media":23218,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"iawp_total_views":9},"restaurant-tag":[],"class_list":["post-23217","restaurant","type-restaurant","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/welcomealghero.com\/es\/wp-json\/wp\/v2\/restaurant\/23217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/welcomealghero.com\/es\/wp-json\/wp\/v2\/restaurant"}],"about":[{"href":"https:\/\/welcomealghero.com\/es\/wp-json\/wp\/v2\/types\/restaurant"}],"replies":[{"embeddable":true,"href":"https:\/\/welcomealghero.com\/es\/wp-json\/wp\/v2\/comments?post=23217"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/welcomealghero.com\/es\/wp-json\/wp\/v2\/media\/23218"}],"wp:attachment":[{"href":"https:\/\/welcomealghero.com\/es\/wp-json\/wp\/v2\/media?parent=23217"}],"wp:term":[{"taxonomy":"restaurant-tag","embeddable":true,"href":"https:\/\/welcomealghero.com\/es\/wp-json\/wp\/v2\/restaurant-tag?post=23217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}