{"id":23581,"date":"2025-01-31T14:57:50","date_gmt":"2025-01-31T14:57:50","guid":{"rendered":"https:\/\/welcomealghero.com\/?post_type=thing-to-do&amp;p=23581"},"modified":"2025-01-31T14:57:50","modified_gmt":"2025-01-31T14:57:50","slug":"church-of-the-misericordia","status":"publish","type":"thing-to-do","link":"https:\/\/welcomealghero.com\/es\/thing-to-do\/church-of-the-misericordia\/","title":{"rendered":"Iglesia de la Misericordia"},"content":{"rendered":"<p>La Iglesia de la Misericordia, construida en el siglo XVII por la Confraternita della Misericordia, est\u00e1 situada en una parte hist\u00f3ricamente significativa de la ciudad. Alberga el venerado Sancristus, un importante emblema durante la Semana Santa que atrae la devota participaci\u00f3n de la comunidad local. Adem\u00e1s, la iglesia cuenta con una imagen del Santo Cristo de Alicante, Espa\u00f1a, que forma parte de las festividades de Semana Santa en Alguer.<\/p>\n<h3 class=\"mb-3 flex space-x-1 text-base\" dir=\"auto\"><span class=\"truncate\">Iglesia de la Misericordia, Alguer <\/span>Resumen<\/h3>\n<div dir=\"auto\">\n<ul>\n<li>\ud83c\udff0\u00a0<strong>Iglesia hist\u00f3rica<\/strong>\u00a0- Construido en 1657, reconstruido a principios del siglo XIX.<\/li>\n<li>\u271d\ufe0f\u00a0<strong>Significado religioso<\/strong>\u00a0- Alberga una estatua de madera de la Virgen del siglo XVII y un crucifijo de \u00e9poca espa\u00f1ola.<\/li>\n<li>\ud83d\udccd\u00a0<strong>Ubicaci\u00f3n central<\/strong>\u00a0- Situado en el casco antiguo de Alghero, lo que facilita su visita.<\/li>\n<li>\ud83c\udfb6\u00a0<strong>Experiencia atmosf\u00e9rica<\/strong>\u00a0- Los visitantes alaban su ambiente tranquilo y la m\u00fasica de \u00f3rgano.<\/li>\n<li>\ud83d\ude4f\u00a0<strong>Retiro espiritual<\/strong>\u00a0- Ideal para meditar o reflexionar en silencio.<\/li>\n<li>\ud83c\udfbc\u00a0<strong>Vespar en directo<\/strong>\u00a0- Las oraciones vespertinas con cantos de monjas crean un ambiente especial.<\/li>\n<li>\u2b50\u00a0<strong>Muy valorado<\/strong>\u00a0- 4,0\/5 en Tripadvisor con cr\u00edticas positivas sobre belleza e historia.<\/li>\n<li>\ud83d\udd25\u00a0<strong>Lugar de visita obligada<\/strong>\u00a0- Recomendado para los amantes de la historia y los que buscan experiencias culturales.<\/li>\n<\/ul>\n<\/div>","protected":false},"featured_media":23839,"template":"","meta":{"_acf_changed":false,"iawp_total_views":4},"class_list":["post-23581","thing-to-do","type-thing-to-do","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/welcomealghero.com\/es\/wp-json\/wp\/v2\/thing-to-do\/23581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/welcomealghero.com\/es\/wp-json\/wp\/v2\/thing-to-do"}],"about":[{"href":"https:\/\/welcomealghero.com\/es\/wp-json\/wp\/v2\/types\/thing-to-do"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/welcomealghero.com\/es\/wp-json\/wp\/v2\/media\/23839"}],"wp:attachment":[{"href":"https:\/\/welcomealghero.com\/es\/wp-json\/wp\/v2\/media?parent=23581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}