{"id":24077,"date":"2025-03-12T10:26:59","date_gmt":"2025-03-12T10:26:59","guid":{"rendered":"https:\/\/welcomealghero.com\/?post_type=activity&#038;p=24077"},"modified":"2026-08-04T14:03:14","modified_gmt":"2026-08-04T14:03:14","slug":"golfo-aranci-kayak-tour-with-dolphins-and-aperitif","status":"publish","type":"activity","link":"https:\/\/welcomealghero.com\/it\/activity\/golfo-aranci-kayak-tour-with-dolphins-and-aperitif\/","title":{"rendered":"Golfo Aranci: tour in kayak con delfini e aperitivo"},"content":{"rendered":"<div class=\"z-layout\" data-v-c3956356=\"\"><span id=\"short-description-adp-text\" class=\"text-atom text-atom--body text-atom--text-regular-sm text-atom\" data-block-id=\"short-description-adp-text\" data-v-c3956356=\"\" data-v-d5b5179d=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Andate in kayak, fate snorkeling e cercate i delfini nelle acque di Golfo Aranci. Ammirate la vita marina, scivolate davanti alle splendide vedute della spiaggia di Cala Moresca e dell'isola di Figarolo e gustate un aperitivo sardo.<\/span><\/span><\/div>\n<div class=\"vertical-layout\" data-v-cc0719f4=\"\">\n<div id=\"travelers-favorite-badge-container\" class=\"z-layout vertical-center passive-click\" data-block-id=\"travelers-favorite-badge-container\" data-v-cc0719f4=\"\" data-v-c3956356=\"\">\n<div id=\"travelers-favorite-badge-content\" class=\"horizontal-layout align-center\" data-block-id=\"travelers-favorite-badge-content\" data-v-c3956356=\"\" data-v-a3e5eb58=\"\">\n<div id=\"travelers-favorite-badge-icon\" class=\"icon-atom\" data-block-id=\"travelers-favorite-badge-icon\" data-v-a3e5eb58=\"\" data-v-8aaaf2e6=\"\"><\/div>\n<p><span id=\"travelers-favorite-badge-title\" class=\"text-atom text-atom--caption-compact-strong text-atom--text-medium-xs text-atom\" data-block-id=\"travelers-favorite-badge-title\" data-v-a3e5eb58=\"\" data-v-d5b5179d=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Apprezzato dagli anglofoni<\/span><\/span><\/p>\n<div id=\"travelers-favorite-badge-divider-container\" class=\"z-layout\" data-block-id=\"travelers-favorite-badge-divider-container\" data-v-a3e5eb58=\"\" data-v-c3956356=\"\">\n<div id=\"travelers-favorite-badge-divider\" class=\"rectangle-atom\" data-gl=\"rectangleAtom\" data-block-id=\"travelers-favorite-badge-divider\" data-v-c3956356=\"\" data-v-67ad146a=\"\"><\/div>\n<\/div>\n<p><span id=\"travelers-favorite-badge-subtitle\" class=\"text-atom text-atom--caption-compact text-atom--text-regular-xs text-atom\" data-block-id=\"travelers-favorite-badge-subtitle\" data-v-a3e5eb58=\"\" data-v-d5b5179d=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Il 94% dei viaggiatori di lingua inglese ha assegnato a questa attivit\u00e0 un punteggio perfetto<\/span><\/span><\/div>\n<\/div>\n<\/div>\n<div class=\"vertical-layout\" data-v-cc0719f4=\"\">\n<div id=\"key-details-vertical-0-horizontal\" class=\"horizontal-layout align-top\" data-block-id=\"key-details-vertical-0-horizontal\" data-v-cc0719f4=\"\" data-v-a3e5eb58=\"\">\n<div id=\"key-details-vertical-0-horizontal-0-vertical\" class=\"vertical-layout\" data-block-id=\"key-details-vertical-0-horizontal-0-vertical\" data-v-a3e5eb58=\"\" data-v-cc0719f4=\"\">\n<div id=\"key-details-row-highlightCancellationPolicy\" class=\"tw:cursor-default horizontal-layout align-top clickable\" tabindex=\"0\" role=\"button\" data-block-id=\"key-details-row-highlightCancellationPolicy\" data-v-cc0719f4=\"\" data-v-a3e5eb58=\"\">\n<div id=\"key-details-vertical-0-horizontal-0-vertical-0-horizontal-0-vertical\" class=\"vertical-layout tw:shrink-0\" data-block-id=\"key-details-vertical-0-horizontal-0-vertical-0-horizontal-0-vertical\" data-v-a3e5eb58=\"\" data-v-cc0719f4=\"\">\n<div id=\"key-details-vertical-0-horizontal-0-vertical-0-horizontal-0-vertical-0-z-layout\" class=\"z-layout vertical-center horizontal-center\" data-block-id=\"key-details-vertical-0-horizontal-0-vertical-0-horizontal-0-vertical-0-z-layout\" data-v-cc0719f4=\"\" data-v-c3956356=\"\">\n<div id=\"key-details-vertical-0-horizontal-0-vertical-0-horizontal-0-vertical-0-z-layout-0-icon\" class=\"icon-atom\" data-block-id=\"key-details-vertical-0-horizontal-0-vertical-0-horizontal-0-vertical-0-z-layout-0-icon\" data-v-c3956356=\"\" data-v-8aaaf2e6=\"\"><\/div>\n<\/div>\n<\/div>\n<div id=\"key-details-vertical-0-horizontal-0-vertical-0-horizontal-1-rect\" class=\"tw:shrink-0 rectangle-atom\" data-gl=\"rectangleAtom\" data-block-id=\"key-details-vertical-0-horizontal-0-vertical-0-horizontal-1-rect\" data-v-a3e5eb58=\"\" data-v-67ad146a=\"\"><\/div>\n<div id=\"key-details-vertical-0-horizontal-0-vertical-0-horizontal-2-z-layout\" class=\"z-layout vertical-center horizontal-start\" data-block-id=\"key-details-vertical-0-horizontal-0-vertical-0-horizontal-2-z-layout\" data-v-a3e5eb58=\"\" data-v-c3956356=\"\">\n<div id=\"key-details-vertical-0-horizontal-0-vertical-0-horizontal-2-z-layout-0-vertical\" class=\"vertical-layout\" data-block-id=\"key-details-vertical-0-horizontal-0-vertical-0-horizontal-2-z-layout-0-vertical\" data-v-c3956356=\"\" data-v-cc0719f4=\"\"><span id=\"key-details-row-highlightCancellationPolicy-title\" class=\"text-atom text-atom--body-highlight text-atom--text-medium-sm text-atom\" data-block-id=\"key-details-row-highlightCancellationPolicy-title\" data-v-cc0719f4=\"\" data-v-d5b5179d=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Cancellazione gratuita<\/span><\/span><span id=\"key-details-row-highlightCancellationPolicy-description\" class=\"text-atom text-atom--caption text-atom--text-regular-xs text-atom\" data-block-id=\"key-details-row-highlightCancellationPolicy-description\" data-v-cc0719f4=\"\" data-v-d5b5179d=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">\u00c8 possibile annullare la prenotazione fino a 24 ore prima per ottenere un rimborso completo<\/span><\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"key-details-vertical-0-horizontal-1-vertical\" class=\"vertical-layout\" data-block-id=\"key-details-vertical-0-horizontal-1-vertical\" data-v-a3e5eb58=\"\" data-v-cc0719f4=\"\">\n<div id=\"key-details-row-reserveNowPayLaterInformation\" class=\"tw:cursor-default horizontal-layout align-top clickable\" tabindex=\"0\" role=\"button\" data-block-id=\"key-details-row-reserveNowPayLaterInformation\" data-v-cc0719f4=\"\" data-v-a3e5eb58=\"\">\n<div id=\"key-details-vertical-0-horizontal-1-vertical-0-horizontal-0-vertical\" class=\"vertical-layout tw:shrink-0\" data-block-id=\"key-details-vertical-0-horizontal-1-vertical-0-horizontal-0-vertical\" data-v-a3e5eb58=\"\" data-v-cc0719f4=\"\">\n<div id=\"key-details-vertical-0-horizontal-1-vertical-0-horizontal-0-vertical-0-z-layout\" class=\"z-layout vertical-center horizontal-center\" data-block-id=\"key-details-vertical-0-horizontal-1-vertical-0-horizontal-0-vertical-0-z-layout\" data-v-cc0719f4=\"\" data-v-c3956356=\"\">\n<div id=\"key-details-vertical-0-horizontal-1-vertical-0-horizontal-0-vertical-0-z-layout-0-icon\" class=\"icon-atom\" data-block-id=\"key-details-vertical-0-horizontal-1-vertical-0-horizontal-0-vertical-0-z-layout-0-icon\" data-v-c3956356=\"\" data-v-8aaaf2e6=\"\"><\/div>\n<\/div>\n<\/div>\n<div id=\"key-details-vertical-0-horizontal-1-vertical-0-horizontal-1-rect\" class=\"tw:shrink-0 rectangle-atom\" data-gl=\"rectangleAtom\" data-block-id=\"key-details-vertical-0-horizontal-1-vertical-0-horizontal-1-rect\" data-v-a3e5eb58=\"\" data-v-67ad146a=\"\"><\/div>\n<div id=\"key-details-vertical-0-horizontal-1-vertical-0-horizontal-2-z-layout\" class=\"z-layout vertical-center horizontal-start\" data-block-id=\"key-details-vertical-0-horizontal-1-vertical-0-horizontal-2-z-layout\" data-v-a3e5eb58=\"\" data-v-c3956356=\"\">\n<div id=\"key-details-vertical-0-horizontal-1-vertical-0-horizontal-2-z-layout-0-vertical\" class=\"vertical-layout\" data-block-id=\"key-details-vertical-0-horizontal-1-vertical-0-horizontal-2-z-layout-0-vertical\" data-v-c3956356=\"\" data-v-cc0719f4=\"\"><span id=\"key-details-row-reserveNowPayLaterInformation-title\" class=\"text-atom text-atom--body-highlight text-atom--text-medium-sm text-atom\" data-block-id=\"key-details-row-reserveNowPayLaterInformation-title\" data-v-cc0719f4=\"\" data-v-d5b5179d=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Prenota ora e paga dopo<\/span><\/span><span id=\"key-details-row-reserveNowPayLaterInformation-description\" class=\"text-atom text-atom--caption text-atom--text-regular-xs text-atom\" data-block-id=\"key-details-row-reserveNowPayLaterInformation-description\" data-v-cc0719f4=\"\" data-v-d5b5179d=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Mantieni flessibili i tuoi piani di viaggio: prenota il tuo posto e oggi non paghi nulla<\/span><\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"key-details-vertical-1-horizontal\" class=\"horizontal-layout align-top\" data-block-id=\"key-details-vertical-1-horizontal\" data-v-cc0719f4=\"\" data-v-a3e5eb58=\"\">\n<div id=\"key-details-vertical-1-horizontal-0-vertical\" class=\"vertical-layout\" data-block-id=\"key-details-vertical-1-horizontal-0-vertical\" data-v-a3e5eb58=\"\" data-v-cc0719f4=\"\">\n<div id=\"key-details-row-duration\" class=\"tw:cursor-default horizontal-layout align-top clickable\" tabindex=\"0\" role=\"button\" data-block-id=\"key-details-row-duration\" data-v-cc0719f4=\"\" data-v-a3e5eb58=\"\">\n<div id=\"key-details-vertical-1-horizontal-0-vertical-0-horizontal-0-vertical\" class=\"vertical-layout tw:shrink-0\" data-block-id=\"key-details-vertical-1-horizontal-0-vertical-0-horizontal-0-vertical\" data-v-a3e5eb58=\"\" data-v-cc0719f4=\"\">\n<div id=\"key-details-vertical-1-horizontal-0-vertical-0-horizontal-0-vertical-0-z-layout\" class=\"z-layout vertical-center horizontal-center\" data-block-id=\"key-details-vertical-1-horizontal-0-vertical-0-horizontal-0-vertical-0-z-layout\" data-v-cc0719f4=\"\" data-v-c3956356=\"\">\n<div id=\"key-details-vertical-1-horizontal-0-vertical-0-horizontal-0-vertical-0-z-layout-0-icon\" class=\"icon-atom\" data-block-id=\"key-details-vertical-1-horizontal-0-vertical-0-horizontal-0-vertical-0-z-layout-0-icon\" data-v-c3956356=\"\" data-v-8aaaf2e6=\"\"><\/div>\n<\/div>\n<\/div>\n<div id=\"key-details-vertical-1-horizontal-0-vertical-0-horizontal-1-rect\" class=\"tw:shrink-0 rectangle-atom\" data-gl=\"rectangleAtom\" data-block-id=\"key-details-vertical-1-horizontal-0-vertical-0-horizontal-1-rect\" data-v-a3e5eb58=\"\" data-v-67ad146a=\"\"><\/div>\n<div id=\"key-details-vertical-1-horizontal-0-vertical-0-horizontal-2-z-layout\" class=\"z-layout vertical-center horizontal-start\" data-block-id=\"key-details-vertical-1-horizontal-0-vertical-0-horizontal-2-z-layout\" data-v-a3e5eb58=\"\" data-v-c3956356=\"\">\n<div id=\"key-details-vertical-1-horizontal-0-vertical-0-horizontal-2-z-layout-0-vertical\" class=\"vertical-layout\" data-block-id=\"key-details-vertical-1-horizontal-0-vertical-0-horizontal-2-z-layout-0-vertical\" data-v-c3956356=\"\" data-v-cc0719f4=\"\"><span id=\"key-details-row-duration-title\" class=\"text-atom text-atom--body-highlight text-atom--text-medium-sm text-atom\" data-block-id=\"key-details-row-duration-title\" data-v-cc0719f4=\"\" data-v-d5b5179d=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Duration 2.5 &#8211; 3 hours<\/span><\/span><span id=\"key-details-row-duration-description\" class=\"text-atom text-atom--caption text-atom--text-regular-xs text-atom\" data-block-id=\"key-details-row-duration-description\" data-v-cc0719f4=\"\" data-v-d5b5179d=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Verifica la disponibilit\u00e0 per conoscere gli orari di inizio<\/span><\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"key-details-vertical-1-horizontal-1-vertical\" class=\"vertical-layout\" data-block-id=\"key-details-vertical-1-horizontal-1-vertical\" data-v-a3e5eb58=\"\" data-v-cc0719f4=\"\">\n<div id=\"key-details-row-fullRefund\" class=\"horizontal-layout align-top\" data-block-id=\"key-details-row-fullRefund\" data-v-cc0719f4=\"\" data-v-a3e5eb58=\"\">\n<div id=\"key-details-vertical-1-horizontal-1-vertical-0-horizontal-0-vertical\" class=\"vertical-layout tw:shrink-0\" data-block-id=\"key-details-vertical-1-horizontal-1-vertical-0-horizontal-0-vertical\" data-v-a3e5eb58=\"\" data-v-cc0719f4=\"\">\n<div id=\"key-details-vertical-1-horizontal-1-vertical-0-horizontal-0-vertical-0-z-layout\" class=\"z-layout vertical-center horizontal-center\" data-block-id=\"key-details-vertical-1-horizontal-1-vertical-0-horizontal-0-vertical-0-z-layout\" data-v-cc0719f4=\"\" data-v-c3956356=\"\">\n<div id=\"key-details-vertical-1-horizontal-1-vertical-0-horizontal-0-vertical-0-z-layout-0-icon\" class=\"icon-atom\" data-block-id=\"key-details-vertical-1-horizontal-1-vertical-0-horizontal-0-vertical-0-z-layout-0-icon\" data-v-c3956356=\"\" data-v-8aaaf2e6=\"\"><\/div>\n<\/div>\n<\/div>\n<div id=\"key-details-vertical-1-horizontal-1-vertical-0-horizontal-1-rect\" class=\"tw:shrink-0 rectangle-atom\" data-gl=\"rectangleAtom\" data-block-id=\"key-details-vertical-1-horizontal-1-vertical-0-horizontal-1-rect\" data-v-a3e5eb58=\"\" data-v-67ad146a=\"\"><\/div>\n<div id=\"key-details-vertical-1-horizontal-1-vertical-0-horizontal-2-z-layout\" class=\"z-layout vertical-center horizontal-start\" data-block-id=\"key-details-vertical-1-horizontal-1-vertical-0-horizontal-2-z-layout\" data-v-a3e5eb58=\"\" data-v-c3956356=\"\">\n<div id=\"key-details-vertical-1-horizontal-1-vertical-0-horizontal-2-z-layout-0-vertical\" class=\"vertical-layout\" data-block-id=\"key-details-vertical-1-horizontal-1-vertical-0-horizontal-2-z-layout-0-vertical\" data-v-c3956356=\"\" data-v-cc0719f4=\"\"><span id=\"key-details-row-fullRefund-title\" class=\"text-atom text-atom--body-highlight text-atom--text-medium-sm text-atom\" data-block-id=\"key-details-row-fullRefund-title\" data-v-cc0719f4=\"\" data-v-d5b5179d=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Full refund offered<\/span><\/span><span id=\"key-details-row-fullRefund-description\" class=\"clamp-with-suffix\" data-block-id=\"key-details-row-fullRefund-description\" data-v-cc0719f4=\"\" data-v-d5b5179d=\"\" data-v-402a23f4=\"\"><span class=\"clamp-with-suffix-content\" data-v-402a23f4=\"\"><span class=\"text-atom text-atom--caption text-atom--text-regular-xs text-atom\" data-v-d5b5179d=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">In case of bad weather, the tour will be canceled and you will be completely refunded.<\/span><\/span><\/span><\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"key-details-vertical-2-horizontal\" class=\"horizontal-layout align-top\" data-block-id=\"key-details-vertical-2-horizontal\" data-v-cc0719f4=\"\" data-v-a3e5eb58=\"\">\n<div id=\"key-details-vertical-2-horizontal-0-vertical\" class=\"vertical-layout\" data-block-id=\"key-details-vertical-2-horizontal-0-vertical\" data-v-a3e5eb58=\"\" data-v-cc0719f4=\"\">\n<div id=\"key-details-row-tourGuides\" class=\"tw:cursor-default horizontal-layout align-top clickable\" tabindex=\"0\" role=\"button\" data-block-id=\"key-details-row-tourGuides\" data-v-cc0719f4=\"\" data-v-a3e5eb58=\"\">\n<div id=\"key-details-vertical-2-horizontal-0-vertical-0-horizontal-0-vertical\" class=\"vertical-layout tw:shrink-0\" data-block-id=\"key-details-vertical-2-horizontal-0-vertical-0-horizontal-0-vertical\" data-v-a3e5eb58=\"\" data-v-cc0719f4=\"\">\n<div id=\"key-details-vertical-2-horizontal-0-vertical-0-horizontal-0-vertical-0-z-layout\" class=\"z-layout vertical-center horizontal-center\" data-block-id=\"key-details-vertical-2-horizontal-0-vertical-0-horizontal-0-vertical-0-z-layout\" data-v-cc0719f4=\"\" data-v-c3956356=\"\">\n<div id=\"key-details-vertical-2-horizontal-0-vertical-0-horizontal-0-vertical-0-z-layout-0-icon\" class=\"icon-atom\" data-block-id=\"key-details-vertical-2-horizontal-0-vertical-0-horizontal-0-vertical-0-z-layout-0-icon\" data-v-c3956356=\"\" data-v-8aaaf2e6=\"\"><\/div>\n<\/div>\n<\/div>\n<div id=\"key-details-vertical-2-horizontal-0-vertical-0-horizontal-1-rect\" class=\"tw:shrink-0 rectangle-atom\" data-gl=\"rectangleAtom\" data-block-id=\"key-details-vertical-2-horizontal-0-vertical-0-horizontal-1-rect\" data-v-a3e5eb58=\"\" data-v-67ad146a=\"\"><\/div>\n<div id=\"key-details-vertical-2-horizontal-0-vertical-0-horizontal-2-z-layout\" class=\"z-layout vertical-center horizontal-start\" data-block-id=\"key-details-vertical-2-horizontal-0-vertical-0-horizontal-2-z-layout\" data-v-a3e5eb58=\"\" data-v-c3956356=\"\">\n<div id=\"key-details-vertical-2-horizontal-0-vertical-0-horizontal-2-z-layout-0-vertical\" class=\"vertical-layout\" data-block-id=\"key-details-vertical-2-horizontal-0-vertical-0-horizontal-2-z-layout-0-vertical\" data-v-c3956356=\"\" data-v-cc0719f4=\"\"><span id=\"key-details-row-tourGuides-title\" class=\"text-atom text-atom--body-highlight text-atom--text-medium-sm text-atom\" data-block-id=\"key-details-row-tourGuides-title\" data-v-cc0719f4=\"\" data-v-d5b5179d=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Guida turistica dal vivo<\/span><\/span><span id=\"key-details-row-tourGuides-description\" class=\"text-atom text-atom--caption text-atom--text-regular-xs text-atom\" data-block-id=\"key-details-row-tourGuides-description\" data-v-cc0719f4=\"\" data-v-d5b5179d=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Inglese, italiano, spagnolo<\/span><\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"key-details-vertical-2-horizontal-1-rect\" class=\"rectangle-atom\" data-gl=\"rectangleAtom\" data-block-id=\"key-details-vertical-2-horizontal-1-rect\" data-v-a3e5eb58=\"\" data-v-67ad146a=\"\"><\/div>\n<\/div>\n<\/div>\n<div class=\"horizontal-layout align-center\" data-v-a3e5eb58=\"\"><span id=\"adp-review-highlights-wtl-info-header-title\" class=\"text-atom text-atom--title-2 text-atom--heading-sm text-atom\" data-block-id=\"adp-review-highlights-wtl-info-header-title\" data-v-a3e5eb58=\"\" data-v-d5b5179d=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">What travelers loved<\/span><\/span><\/p>\n<div id=\"adp-review-highlights-wtl-info-header-icon-container\" class=\"z-layout clickable\" tabindex=\"0\" role=\"button\" data-block-id=\"adp-review-highlights-wtl-info-header-icon-container\" data-v-a3e5eb58=\"\" data-v-c3956356=\"\">\n<div id=\"adp-review-highlights-wtl-info-header-icon\" class=\"icon-atom\" data-block-id=\"adp-review-highlights-wtl-info-header-icon\" data-v-c3956356=\"\" data-v-8aaaf2e6=\"\"><\/div>\n<\/div>\n<\/div>\n<div id=\"highlighted-reviews-container\" class=\"highlighted-review-desktop-container-block\" data-v-7fef7c67=\"\" data-block-id=\"highlighted-reviews-container\">\n<section class=\"highlighted-review-desktop-container-view\" data-v-7fef7c67=\"\" data-v-b52b9b0d=\"\">\n<div class=\"highlighted-review-desktop-container-view__reviews-block-container\" data-v-b52b9b0d=\"\">\n<div class=\"highlighted-review-desktop-container-block__review-block\" data-v-7fef7c67=\"\">\n<div class=\"highlighted-review-block-wrapper\" data-v-7fef7c67=\"\" data-v-cb91b672=\"\" data-block-id=\"highlightedReview-review-highlights-126139887\">\n<div class=\"visibility-tracking-container highlighted-review-block\" data-test-id=\"\" data-v-cb91b672=\"\" data-v-4c01bd86=\"\">\n<div class=\"review-highlight-card__container v2-styles review-highlight-card__container--v2\" data-v-4c01bd86=\"\">\n<div class=\"rating-star rating-star--small review-highlight-card\" aria-labelledby=\"v-2-1-2-0-rating-star__aria-description\" data-v-4c01bd86=\"\" data-v-106e5a83=\"\"><span class=\"rating-star__label\" aria-hidden=\"true\" data-v-106e5a83=\"\">5<\/span><\/p>\n<div id=\"v-2-1-2-0-rating-star__aria-description\" class=\"sr-only\" data-v-106e5a83=\"\">5 stelle su 5<\/div>\n<\/div>\n<div id=\"review-author-review-highlights-review-126139887\" class=\"review-card__author\" data-v-cb91b672=\"\" data-v-62e21c53=\"\" data-v-9a6cad18=\"\">\n<div class=\"review-card__author-photo\" data-v-9a6cad18=\"\"><span class=\"review-card__author-initial\" data-test-id=\"review-card-author-initial\" data-v-62e21c53=\"\" data-v-c526bdeb=\"\"><span class=\"text-atom text-atom--title-2 text-atom--heading-sm\" data-v-62e21c53=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">G<\/span><\/span><\/span><\/div>\n<div class=\"review-card__author-details\" data-v-9a6cad18=\"\"><span class=\"review-card__author-details-name\" data-v-9a6cad18=\"\"><span class=\"text-atom text-atom--caption-strong text-atom--text-medium-xs\" data-v-62e21c53=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Georgette \u2013 Germania<\/span><\/span><\/span><span class=\"review-card__author-details-name-legend\" data-v-9a6cad18=\"\"><span class=\"review-card___author-date\" data-v-9a6cad18=\"\"><span class=\"text-atom text-atom--caption text-atom--text-regular-xs\" data-v-62e21c53=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">August 2, 2026 &#8211; Verified booking<\/span><\/span><\/span><\/span><\/div>\n<\/div>\n<section class=\"toggle-content\" data-v-4c01bd86=\"\" data-v-599dc971=\"\">\n<div class=\"toggle-content__body\" dir=\"auto\" data-v-599dc971=\"\">\n<div class=\"toggle-content__content toggle-content__content--packable\" data-test-id=\"toggle-content\" data-test-state=\"collapsed\" data-v-599dc971=\"\">\n<p class=\"review-highlight-card__text--v2 review-highlight-card__text\" data-v-4c01bd86=\"\"><span class=\"text-atom text-atom--body text-atom--text-regular-xs\" data-v-cb91b672=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">The trip with Sarah (marine biologist), and Luca (local young man), was a pleasure. They were both very nice, experienced and well prepared. They looked after each and every member of the trip. We &#8211; me and my daughter- were last in the row and one of them was always at our side. The trip was well organized, just like explained on the website, and pleasant. We enjoyed the scenery a lot, the snorkeling and swimming. We saw dolphins as well!!! The snacks were extremely delicious- 2 local cheeses and local meat cuts, with olives and beverages. The information and stories were just the right amount, so no boring unending tales. And our questions were answered to the point. I definitely recommend it, especially that it is 100% nature friendly, and the guys are awesome!<\/span><\/span><\/p>\n<\/div>\n<div class=\"toggle-content__label-placeholder toggle-content__label-placeholder--inline\" data-v-599dc971=\"\"><button class=\"c-button c-button--medium c-button--text c-button--text-standard toggle-content__label\" type=\"button\" data-v-599dc971=\"\" data-test-id=\"read-more-button\" aria-label=\"\"><span class=\"c-button__text\"><span data-v-599dc971=\"\" data-test-id=\"see-less-button\">Per saperne di pi\u00f9<\/span><\/span><\/button><\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"highlighted-review-desktop-container-block__review-block\" data-v-7fef7c67=\"\">\n<div class=\"highlighted-review-block-wrapper\" data-v-7fef7c67=\"\" data-v-cb91b672=\"\" data-block-id=\"highlightedReview-review-highlights-126110822\">\n<div class=\"visibility-tracking-container highlighted-review-block\" data-test-id=\"\" data-v-cb91b672=\"\" data-v-4c01bd86=\"\">\n<div class=\"review-highlight-card__container v2-styles review-highlight-card__container--v2\" data-v-4c01bd86=\"\">\n<div class=\"rating-star rating-star--small review-highlight-card\" aria-labelledby=\"v-2-1-2-1-rating-star__aria-description\" data-v-4c01bd86=\"\" data-v-106e5a83=\"\"><span class=\"rating-star__label\" aria-hidden=\"true\" data-v-106e5a83=\"\">5<\/span><\/p>\n<div id=\"v-2-1-2-1-rating-star__aria-description\" class=\"sr-only\" data-v-106e5a83=\"\">5 stelle su 5<\/div>\n<\/div>\n<div id=\"review-author-review-highlights-review-126110822\" class=\"review-card__author\" data-v-cb91b672=\"\" data-v-62e21c53=\"\" data-v-9a6cad18=\"\">\n<div class=\"review-card__author-photo\" data-v-9a6cad18=\"\"><span class=\"review-card__author-initial\" data-test-id=\"review-card-author-initial\" data-v-62e21c53=\"\" data-v-c526bdeb=\"\"><span class=\"text-atom text-atom--title-2 text-atom--heading-sm\" data-v-62e21c53=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">O<\/span><\/span><\/span><\/div>\n<div class=\"review-card__author-details\" data-v-9a6cad18=\"\"><span class=\"review-card__author-details-name\" data-v-9a6cad18=\"\"><span class=\"text-atom text-atom--caption-strong text-atom--text-medium-xs\" data-v-62e21c53=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Orsolya \u2013 Ungheria<\/span><\/span><\/span><span class=\"review-card__author-details-name-legend\" data-v-9a6cad18=\"\"><span class=\"review-card___author-date\" data-v-9a6cad18=\"\"><span class=\"text-atom text-atom--caption text-atom--text-regular-xs\" data-v-62e21c53=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">August 1, 2026 &#8211; Verified booking<\/span><\/span><\/span><\/span><\/div>\n<\/div>\n<section class=\"toggle-content\" data-v-4c01bd86=\"\" data-v-599dc971=\"\">\n<div class=\"toggle-content__body\" dir=\"auto\" data-v-599dc971=\"\">\n<div class=\"toggle-content__content toggle-content__content--packable\" data-test-id=\"toggle-content\" data-test-state=\"collapsed\" data-v-599dc971=\"\">\n<p class=\"review-highlight-card__text--v2 review-highlight-card__text\" data-v-4c01bd86=\"\"><span class=\"text-atom text-atom--body text-atom--text-regular-xs\" data-v-cb91b672=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Un'esperienza meravigliosa e unica! Alice e Sarah sono state incredibilmente premurose, ci hanno aiutato con i kayak e ci hanno fornito informazioni interessanti sulla fauna marina locale. Abbiamo avuto la fortuna di vedere i delfini da vicino, il che ha reso l'escursione ancora pi\u00f9 speciale. \u00c8 stata un'esperienza davvero tranquilla e indimenticabile. L'aperitivo \u00e8 stato un tocco di classe e il modo perfetto per concludere il tour. Consiglio vivamente questa escursione: 10\/10!<\/span><\/span><\/p>\n<\/div>\n<div class=\"toggle-content__label-placeholder toggle-content__label-placeholder--inline\" data-v-599dc971=\"\"><button class=\"c-button c-button--medium c-button--text c-button--text-standard toggle-content__label\" type=\"button\" data-v-599dc971=\"\" data-test-id=\"read-more-button\" aria-label=\"\"><span class=\"c-button__text\"><span data-v-599dc971=\"\" data-test-id=\"see-less-button\">Per saperne di pi\u00f9<\/span><\/span><\/button><\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"highlighted-review-desktop-container-view__see-more-reviews-button\" data-v-b52b9b0d=\"\"><button class=\"c-button c-button--medium c-button--text c-button--text-secondary highlighted-review-desktop-container-block__see-more-reviews-button\" type=\"button\" data-test-id=\"see-more-reviews-button\" data-v-7fef7c67=\"\" data-v-501f8538=\"\"><span class=\"c-button__text\"><span class=\"text-atom\" data-v-501f8538=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">See more reviews<\/span><\/span><\/span><\/button><\/div>\n<\/section>\n<\/div>\n<div id=\"highlights-point-top-spacer\" class=\"container\" data-block-id=\"highlights-point-top-spacer\"><\/div>\n<div id=\"row-highlights-point-header-content\" class=\"row container\" data-v-618ead3b=\"\" data-block-id=\"row-highlights-point-header-content\">\n<div class=\"row__column__wrapper\" data-v-618ead3b=\"\">\n<div class=\"row__column\" data-v-618ead3b=\"\">\n<div class=\"z-layout\" data-v-c3956356=\"\">\n<h2 id=\"highlights-point-header-text\" class=\"text-atom text-atom--title-3 text-atom--heading-xs text-atom\" data-block-id=\"highlights-point-header-text\" data-v-c3956356=\"\" data-v-d5b5179d=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Punti salienti<\/span><\/h2>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"row__column__wrapper\" data-v-618ead3b=\"\">\n<div class=\"row__column\" data-v-618ead3b=\"\">\n<div id=\"highlights-point\" class=\"text-list-block\" data-v-04fa1704=\"\" data-block-id=\"highlights-point\">\n<section class=\"toggle-content\" data-v-04fa1704=\"\" data-v-dfbf3dcb=\"\">\n<div class=\"toggle-content__content\" data-test-id=\"toggle-content\" data-test-state=\"collapsed\" data-v-dfbf3dcb=\"\">\n<ul data-test-id=\"text-list-block-list\" data-v-04fa1704=\"\">\n<li data-v-04fa1704=\"\"><span class=\"text-atom text-atom--body text-atom--text-regular-sm\" data-v-04fa1704=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Prova l'esperienza di nuotare e fare snorkeling con i biologi marini su un'isola deserta<\/span><\/span><\/li>\n<li data-v-04fa1704=\"\"><span class=\"text-atom text-atom--body text-atom--text-regular-sm\" data-v-04fa1704=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Goditi una colazione o un aperitivo su una delle spiagge pi\u00f9 belle della Sardegna<\/span><\/span><\/li>\n<li data-v-04fa1704=\"\"><span class=\"text-atom text-atom--body text-atom--text-regular-sm\" data-v-04fa1704=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Visita un\u2019area protetta e ammira la fauna selvatica, come i delfini che nuotano vicino al kayak<\/span><\/span><\/li>\n<li data-v-04fa1704=\"\"><span class=\"text-atom text-atom--body text-atom--text-regular-sm\" data-v-04fa1704=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Esplora la fauna marina e cogli l\u2019occasione di avvistare i delfini che vivono in queste acque<\/span><\/span><\/li>\n<li data-v-04fa1704=\"\"><span class=\"text-atom text-atom--body text-atom--text-regular-sm\" data-v-04fa1704=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Vivi il brivido dell'avventura guidato da professionisti esperti<\/span><\/span><\/li>\n<\/ul>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"highlights-point-bottom-spacer\" class=\"container\" data-block-id=\"highlights-point-bottom-spacer\"><\/div>\n<div class=\"z-layout\" data-v-c3956356=\"\">\n<div id=\"additional-details-separator-1-rectangle\" class=\"z-layout\" data-block-id=\"additional-details-separator-1-rectangle\" data-v-c3956356=\"\"><\/div>\n<\/div>\n<div id=\"full-description-top-spacer\" class=\"container\" data-block-id=\"full-description-top-spacer\"><\/div>\n<div id=\"row-full-description-header-content\" class=\"row container\" data-v-618ead3b=\"\" data-block-id=\"row-full-description-header-content\">\n<div class=\"row__column__wrapper\" data-v-618ead3b=\"\">\n<div class=\"row__column\" data-v-618ead3b=\"\">\n<div class=\"z-layout\" data-v-c3956356=\"\">\n<h2 id=\"full-description-header-text\" class=\"text-atom text-atom--title-3 text-atom--heading-xs text-atom\" data-block-id=\"full-description-header-text\" data-v-c3956356=\"\" data-v-d5b5179d=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Descrizione completa<\/span><\/h2>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"row__column__wrapper\" data-v-618ead3b=\"\">\n<div class=\"row__column\" data-v-618ead3b=\"\">\n<div id=\"full-description-text-list\" class=\"text-list-block\" data-v-04fa1704=\"\" data-block-id=\"full-description-text-list\">\n<section class=\"toggle-content\" data-v-04fa1704=\"\" data-v-dfbf3dcb=\"\">\n<div class=\"toggle-content__content toggle-content__content--expanded toggle-content__content--packable\" data-test-id=\"toggle-content\" data-test-state=\"expanded\" data-v-dfbf3dcb=\"\">\n<p>Experience the thrill of kayaking and snorkeling with marine biologists in the beautiful waters of Golfo Aranci with this day tour. Search for dolphins and enjoy a traditional Sardinian aperitif to complete your experience.<\/p>\n<p>Join your guides and depart from the renowned Spiaggia dei Baracconi Beach. Your guides will choose the best route based on daily conditions to ensure you have the best adventure.<\/p>\n<p>Visit some of the area&#8217;s highlights, such as Cala Moresca, known for its incredible colors and natural surroundings, and the secluded island of Figarolo, which can only be accessed by kayak.<\/p>\n<p>Visit a fish farm in the middle of the sea well known for its resident dolphin colony. Before returning to the starting point, enjoy a traditional Sardinian aperitif on the paradise-like island of Figarolo.<\/p>\n<\/div>\n<div class=\"toggle-content__label-placeholder toggle-content__label-btn-height\" data-v-dfbf3dcb=\"\"><button class=\"c-button c-button--medium c-button--text c-button--text-standard toggle-content__button\" type=\"button\" data-v-dfbf3dcb=\"\" aria-label=\"\"><span class=\"c-button__text\"><span class=\"text-atom text-atom--body-strong text-atom--text-medium-sm\" data-v-ebc78423=\"\" data-v-04fa1704=\"\" data-test-id=\"expanded-button-text\"><span class=\"\" data-v-ebc78423=\"\">See less<\/span><\/span><\/span><\/button><\/div>\n<\/section>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"full-description-bottom-spacer\" class=\"container\" data-block-id=\"full-description-bottom-spacer\"><\/div>\n<div class=\"z-layout\" data-v-c3956356=\"\">\n<div id=\"additional-details-separator-2-rectangle\" class=\"z-layout\" data-block-id=\"additional-details-separator-2-rectangle\" data-v-c3956356=\"\"><\/div>\n<\/div>\n<div id=\"inclusions-top-spacer\" class=\"container\" data-block-id=\"inclusions-top-spacer\"><\/div>\n<div id=\"row-inclusions-header-content\" class=\"row container\" data-v-618ead3b=\"\" data-block-id=\"row-inclusions-header-content\">\n<div class=\"row__column__wrapper\" data-v-618ead3b=\"\">\n<div class=\"row__column\" data-v-618ead3b=\"\">\n<div class=\"z-layout\" data-v-c3956356=\"\">\n<h2 id=\"inclusions-header-text\" class=\"text-atom text-atom--title-3 text-atom--heading-xs text-atom\" data-block-id=\"inclusions-header-text\" data-v-c3956356=\"\" data-v-d5b5179d=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Includes<\/span><\/h2>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"row__column__wrapper\" data-v-618ead3b=\"\">\n<div class=\"row__column\" data-v-618ead3b=\"\">\n<div class=\"horizontal-layout align-top\" data-v-a3e5eb58=\"\">\n<div id=\"inclusion-0-horizontal-0-icon\" class=\"icon-atom\" data-block-id=\"inclusion-0-horizontal-0-icon\" data-v-a3e5eb58=\"\" data-v-8aaaf2e6=\"\"><\/div>\n<p><span id=\"inclusion-0-horizontal-1-title-text\" class=\"text-atom text-atom--body text-atom--text-regular-sm text-atom\" data-block-id=\"inclusion-0-horizontal-1-title-text\" data-v-a3e5eb58=\"\" data-v-d5b5179d=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Trasferimento da e per l'hotel (se si sceglie questa opzione)<\/span><\/span><\/div>\n<div class=\"horizontal-layout align-top\" data-v-a3e5eb58=\"\">\n<div id=\"inclusion-1-horizontal-0-icon\" class=\"icon-atom\" data-block-id=\"inclusion-1-horizontal-0-icon\" data-v-a3e5eb58=\"\" data-v-8aaaf2e6=\"\"><\/div>\n<p><span id=\"inclusion-1-horizontal-1-title-text\" class=\"text-atom text-atom--body text-atom--text-regular-sm text-atom\" data-block-id=\"inclusion-1-horizontal-1-title-text\" data-v-a3e5eb58=\"\" data-v-d5b5179d=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Kayak<\/span><\/span><\/div>\n<div class=\"horizontal-layout align-top\" data-v-a3e5eb58=\"\">\n<div id=\"inclusion-2-horizontal-0-icon\" class=\"icon-atom\" data-block-id=\"inclusion-2-horizontal-0-icon\" data-v-a3e5eb58=\"\" data-v-8aaaf2e6=\"\"><\/div>\n<p><span id=\"inclusion-2-horizontal-1-title-text\" class=\"text-atom text-atom--body text-atom--text-regular-sm text-atom\" data-block-id=\"inclusion-2-horizontal-1-title-text\" data-v-a3e5eb58=\"\" data-v-d5b5179d=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Giubbotto di salvataggio<\/span><\/span><\/div>\n<div class=\"horizontal-layout align-top\" data-v-a3e5eb58=\"\">\n<div id=\"inclusion-3-horizontal-0-icon\" class=\"icon-atom\" data-block-id=\"inclusion-3-horizontal-0-icon\" data-v-a3e5eb58=\"\" data-v-8aaaf2e6=\"\"><\/div>\n<p><span id=\"inclusion-3-horizontal-1-title-text\" class=\"text-atom text-atom--body text-atom--text-regular-sm text-atom\" data-block-id=\"inclusion-3-horizontal-1-title-text\" data-v-a3e5eb58=\"\" data-v-d5b5179d=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Borsa impermeabile per portafoglio e chiavi dell'auto<\/span><\/span><\/div>\n<div class=\"horizontal-layout align-top\" data-v-a3e5eb58=\"\">\n<div id=\"inclusion-4-horizontal-0-icon\" class=\"icon-atom\" data-block-id=\"inclusion-4-horizontal-0-icon\" data-v-a3e5eb58=\"\" data-v-8aaaf2e6=\"\"><\/div>\n<p><span id=\"inclusion-4-horizontal-1-title-text\" class=\"text-atom text-atom--body text-atom--text-regular-sm text-atom\" data-block-id=\"inclusion-4-horizontal-1-title-text\" data-v-a3e5eb58=\"\" data-v-d5b5179d=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Lezione di kayak<\/span><\/span><\/div>\n<div class=\"horizontal-layout align-top\" data-v-a3e5eb58=\"\">\n<div id=\"inclusion-5-horizontal-0-icon\" class=\"icon-atom\" data-block-id=\"inclusion-5-horizontal-0-icon\" data-v-a3e5eb58=\"\" data-v-8aaaf2e6=\"\"><\/div>\n<p><span id=\"inclusion-5-horizontal-1-title-text\" class=\"text-atom text-atom--body text-atom--text-regular-sm text-atom\" data-block-id=\"inclusion-5-horizontal-1-title-text\" data-v-a3e5eb58=\"\" data-v-d5b5179d=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Maschere per lo snorkeling<\/span><\/span><\/div>\n<div class=\"horizontal-layout align-top\" data-v-a3e5eb58=\"\">\n<div id=\"inclusion-6-horizontal-0-icon\" class=\"icon-atom\" data-block-id=\"inclusion-6-horizontal-0-icon\" data-v-a3e5eb58=\"\" data-v-8aaaf2e6=\"\"><\/div>\n<p><span id=\"inclusion-6-horizontal-1-title-text\" class=\"text-atom text-atom--body text-atom--text-regular-sm text-atom\" data-block-id=\"inclusion-6-horizontal-1-title-text\" data-v-a3e5eb58=\"\" data-v-d5b5179d=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Tipico aperitivo sardo<\/span><\/span><\/div>\n<div class=\"horizontal-layout align-top\" data-v-a3e5eb58=\"\">\n<div id=\"exclusion-0-horizontal-0-icon\" class=\"icon-atom\" data-block-id=\"exclusion-0-horizontal-0-icon\" data-v-a3e5eb58=\"\" data-v-8aaaf2e6=\"\"><\/div>\n<p><span id=\"exclusion-0-horizontal-1-title-text\" class=\"text-atom text-atom--body text-atom--text-regular-sm text-atom\" data-block-id=\"exclusion-0-horizontal-1-title-text\" data-v-a3e5eb58=\"\" data-v-d5b5179d=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Servizi fotografici e video<\/span><\/span><\/div>\n<div class=\"horizontal-layout align-top\" data-v-a3e5eb58=\"\">\n<div id=\"exclusion-1-horizontal-0-icon\" class=\"icon-atom\" data-block-id=\"exclusion-1-horizontal-0-icon\" data-v-a3e5eb58=\"\" data-v-8aaaf2e6=\"\"><\/div>\n<p><span id=\"exclusion-1-horizontal-1-title-text\" class=\"text-atom text-atom--body text-atom--text-regular-sm text-atom\" data-block-id=\"exclusion-1-horizontal-1-title-text\" data-v-a3e5eb58=\"\" data-v-d5b5179d=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Tariffe di parcheggio<\/span><\/span><\/div>\n<div class=\"horizontal-layout align-top\" data-v-a3e5eb58=\"\">\n<div id=\"exclusion-2-horizontal-0-icon\" class=\"icon-atom\" data-block-id=\"exclusion-2-horizontal-0-icon\" data-v-a3e5eb58=\"\" data-v-8aaaf2e6=\"\"><\/div>\n<p><span id=\"exclusion-2-horizontal-1-title-text\" class=\"text-atom text-atom--body text-atom--text-regular-sm text-atom\" data-block-id=\"exclusion-2-horizontal-1-title-text\" data-v-a3e5eb58=\"\" data-v-d5b5179d=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Suggerimenti<\/span><\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"inclusions-bottom-spacer\" class=\"container\" data-block-id=\"inclusions-bottom-spacer\"><\/div>\n<div class=\"z-layout\" data-v-c3956356=\"\">\n<div id=\"additional-details-separator-3-rectangle\" class=\"z-layout\" data-block-id=\"additional-details-separator-3-rectangle\" data-v-c3956356=\"\"><\/div>\n<\/div>\n<div id=\"not-suitable-for-top-spacer\" class=\"container\" data-block-id=\"not-suitable-for-top-spacer\"><\/div>\n<div id=\"row-not-suitable-for-header-content\" class=\"row container\" data-v-618ead3b=\"\" data-block-id=\"row-not-suitable-for-header-content\">\n<div class=\"row__column__wrapper\" data-v-618ead3b=\"\">\n<div class=\"row__column\" data-v-618ead3b=\"\">\n<div class=\"z-layout\" data-v-c3956356=\"\">\n<h2 id=\"not-suitable-for-header-text\" class=\"text-atom text-atom--title-3 text-atom--heading-xs text-atom\" data-block-id=\"not-suitable-for-header-text\" data-v-c3956356=\"\" data-v-d5b5179d=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Non adatto a<\/span><\/h2>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"row__column__wrapper\" data-v-618ead3b=\"\">\n<div class=\"row__column\" data-v-618ead3b=\"\">\n<div id=\"not-suitable-for-point\" class=\"text-list-block\" data-v-04fa1704=\"\" data-block-id=\"not-suitable-for-point\">\n<section class=\"toggle-content\" data-v-04fa1704=\"\" data-v-dfbf3dcb=\"\">\n<div class=\"toggle-content__content\" data-test-id=\"toggle-content\" data-test-state=\"collapsed\" data-v-dfbf3dcb=\"\">\n<ul data-test-id=\"text-list-block-list\" data-v-04fa1704=\"\">\n<li data-v-04fa1704=\"\"><span class=\"text-atom text-atom--body text-atom--text-regular-sm\" data-v-04fa1704=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Bambini di et\u00e0 inferiore ai 4 anni<\/span><\/span><\/li>\n<li data-v-04fa1704=\"\"><span class=\"text-atom text-atom--body text-atom--text-regular-sm\" data-v-04fa1704=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Persone di peso superiore a 220 libbre (100 kg)<\/span><\/span><\/li>\n<li data-v-04fa1704=\"\"><span class=\"text-atom text-atom--body text-atom--text-regular-sm\" data-v-04fa1704=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Persone di et\u00e0 superiore ai 70 anni<\/span><\/span><\/li>\n<\/ul>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"not-suitable-for-bottom-spacer\" class=\"container\" data-block-id=\"not-suitable-for-bottom-spacer\"><\/div>\n<div class=\"z-layout\" data-v-c3956356=\"\">\n<div id=\"additional-details-separator-4-rectangle\" class=\"z-layout\" data-block-id=\"additional-details-separator-4-rectangle\" data-v-c3956356=\"\"><\/div>\n<\/div>\n<div id=\"meeting-points-top-spacer\" class=\"container\" data-block-id=\"meeting-points-top-spacer\"><\/div>\n<div id=\"row-meeting-points-header-content\" class=\"row container\" data-v-618ead3b=\"\" data-block-id=\"row-meeting-points-header-content\">\n<div class=\"row__column__wrapper\" data-v-618ead3b=\"\">\n<div class=\"row__column\" data-v-618ead3b=\"\">\n<div class=\"z-layout\" data-v-c3956356=\"\">\n<h2 id=\"meeting-points-header-text\" class=\"text-atom text-atom--title-3 text-atom--heading-xs text-atom\" data-block-id=\"meeting-points-header-text\" data-v-c3956356=\"\" data-v-d5b5179d=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Punto di ritrovo<\/span><\/h2>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"row__column__wrapper\" data-v-618ead3b=\"\">\n<div class=\"row__column\" data-v-618ead3b=\"\">\n<div id=\"meeting-point-links\" class=\"meeting-points-block\" data-v-9885bfa3=\"\" data-block-id=\"meeting-point-links\"><span class=\"text-atom text-atom--body\" data-v-9885bfa3=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Search for \u201cSpiaggia dei Baracconi\u201d or \u201cKayaking Moresca\u201d on Google Maps. Once you arrive, after going down past the bridge, continue straight for about 100 meters. You will find a white fence by the sea, with orange canoes nearby. Your guides will be there waiting for you.<\/span><\/span><\/p>\n<ul class=\"links\" data-v-9885bfa3=\"\">\n<li class=\"\" data-v-9885bfa3=\"\"><a class=\"c-button c-button--medium c-button--text c-button--text-standard c-button--with-icon c-button--with-trailing-icon link-button\" href=\"https:\/\/maps.google.com\/?q=@40.988908133872755,9.633552727539056\" target=\"_blank\" rel=\"noopener noreferrer\" data-v-9885bfa3=\"\" data-v-501f8538=\"\"><span class=\"c-button__text\"><span class=\"text-atom text-atom--body text-atom--text-regular-sm\" data-v-501f8538=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Apri su Google Maps<\/span><\/span><\/span><\/a><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"meeting-points-bottom-spacer\" class=\"container\" data-block-id=\"meeting-points-bottom-spacer\"><\/div>\n<div class=\"z-layout\" data-v-c3956356=\"\">\n<div id=\"additional-details-separator-5-rectangle\" class=\"z-layout\" data-block-id=\"additional-details-separator-5-rectangle\" data-v-c3956356=\"\"><\/div>\n<\/div>\n<div id=\"important-information-top-spacer\" class=\"container\" data-block-id=\"important-information-top-spacer\"><\/div>\n<div id=\"row-important-information-header-content\" class=\"row container\" data-v-618ead3b=\"\" data-block-id=\"row-important-information-header-content\">\n<div class=\"row__column__wrapper\" data-v-618ead3b=\"\">\n<div class=\"row__column\" data-v-618ead3b=\"\">\n<div class=\"z-layout\" data-v-c3956356=\"\">\n<h2 id=\"important-information-header-text\" class=\"text-atom text-atom--title-3 text-atom--heading-xs text-atom\" data-block-id=\"important-information-header-text\" data-v-c3956356=\"\" data-v-d5b5179d=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Informazioni importanti<\/span><\/h2>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"row__column__wrapper\" data-v-618ead3b=\"\">\n<div class=\"row__column\" data-v-618ead3b=\"\">\n<div class=\"z-layout\" data-v-c3956356=\"\">\n<h2 id=\"what-to-bring-header-text\" class=\"text-atom text-atom--body-strong text-atom--text-medium-sm text-atom\" data-block-id=\"what-to-bring-header-text\" data-v-c3956356=\"\" data-v-d5b5179d=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">What to bring<\/span><\/h2>\n<\/div>\n<div id=\"what-to-bring-header-spacer\" class=\"container\" data-block-id=\"what-to-bring-header-spacer\"><\/div>\n<div id=\"what-to-bring-point\" class=\"text-list-block\" data-v-04fa1704=\"\" data-block-id=\"what-to-bring-point\">\n<section class=\"toggle-content\" data-v-04fa1704=\"\" data-v-dfbf3dcb=\"\">\n<div class=\"toggle-content__content\" data-test-id=\"toggle-content\" data-test-state=\"collapsed\" data-v-dfbf3dcb=\"\">\n<ul data-test-id=\"text-list-block-list\" data-v-04fa1704=\"\">\n<li data-v-04fa1704=\"\"><span class=\"text-atom text-atom--body text-atom--text-regular-sm\" data-v-04fa1704=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Sun hat<\/span><\/span><\/li>\n<li data-v-04fa1704=\"\"><span class=\"text-atom text-atom--body text-atom--text-regular-sm\" data-v-04fa1704=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Asciugamano<\/span><\/span><\/li>\n<li data-v-04fa1704=\"\"><span class=\"text-atom text-atom--body text-atom--text-regular-sm\" data-v-04fa1704=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Sunscreen<\/span><\/span><\/li>\n<li data-v-04fa1704=\"\"><span class=\"text-atom text-atom--body text-atom--text-regular-sm\" data-v-04fa1704=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Water shoes<\/span><\/span><\/li>\n<\/ul>\n<\/div>\n<\/section>\n<\/div>\n<div id=\"what-to-bring-section-bottom-spacer-1\" class=\"container\" data-block-id=\"what-to-bring-section-bottom-spacer-1\"><\/div>\n<div class=\"z-layout\" data-v-c3956356=\"\">\n<h2 id=\"not-allowed-header-text\" class=\"text-atom text-atom--body-strong text-atom--text-medium-sm text-atom\" data-block-id=\"not-allowed-header-text\" data-v-c3956356=\"\" data-v-d5b5179d=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Non consentito<\/span><\/h2>\n<\/div>\n<div id=\"not-allowed-header-spacer\" class=\"container\" data-block-id=\"not-allowed-header-spacer\"><\/div>\n<div id=\"not-allowed-point\" class=\"text-list-block\" data-v-04fa1704=\"\" data-block-id=\"not-allowed-point\">\n<section class=\"toggle-content\" data-v-04fa1704=\"\" data-v-dfbf3dcb=\"\">\n<div class=\"toggle-content__content\" data-test-id=\"toggle-content\" data-test-state=\"collapsed\" data-v-dfbf3dcb=\"\">\n<ul data-test-id=\"text-list-block-list\" data-v-04fa1704=\"\">\n<li data-v-04fa1704=\"\"><span class=\"text-atom text-atom--body text-atom--text-regular-sm\" data-v-04fa1704=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Bagagli o borse di grandi dimensioni<\/span><\/span><\/li>\n<li data-v-04fa1704=\"\"><span class=\"text-atom text-atom--body text-atom--text-regular-sm\" data-v-04fa1704=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Alcol e droghe<\/span><\/span><\/li>\n<\/ul>\n<\/div>\n<\/section>\n<\/div>\n<div id=\"what-to-bring-section-bottom-spacer-2\" class=\"container\" data-block-id=\"what-to-bring-section-bottom-spacer-2\"><\/div>\n<div class=\"z-layout\" data-v-c3956356=\"\">\n<h2 id=\"good-to-know-header-text\" class=\"text-atom text-atom--body-strong text-atom--text-medium-sm text-atom\" data-block-id=\"good-to-know-header-text\" data-v-c3956356=\"\" data-v-d5b5179d=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Informazioni utili prima di partire<\/span><\/h2>\n<\/div>\n<div id=\"good-to-know-header-spacer\" class=\"container\" data-block-id=\"good-to-know-header-spacer\"><\/div>\n<div id=\"good-to-know-point\" class=\"text-list-block\" data-v-04fa1704=\"\" data-block-id=\"good-to-know-point\">\n<section class=\"toggle-content\" data-v-04fa1704=\"\" data-v-dfbf3dcb=\"\">\n<div class=\"toggle-content__content toggle-content__content--expanded toggle-content__content--packable\" data-test-id=\"toggle-content\" data-test-state=\"expanded\" data-v-dfbf3dcb=\"\">\n<ul data-test-id=\"text-list-block-list\" data-v-04fa1704=\"\">\n<li data-v-04fa1704=\"\"><span class=\"text-atom text-atom--body text-atom--text-regular-sm\" data-v-04fa1704=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">&#8211; In case of bad weather, the tour will be canceled and you will be completely refunded.<\/span><\/span><\/li>\n<li data-v-04fa1704=\"\"><span class=\"text-atom text-atom--body text-atom--text-regular-sm\" data-v-04fa1704=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">&#8211; Whatsapp messages\/ Imessage is the main communication channel between supplier\/customers for informations or cancellations .<\/span><\/span><\/li>\n<li data-v-04fa1704=\"\"><span class=\"text-atom text-atom--body text-atom--text-regular-sm\" data-v-04fa1704=\"\" data-v-ebc78423=\"\"><span class=\"\" data-v-ebc78423=\"\">Please don&#8217;t forget to add your prefix number during the booking procedure<\/span><\/span><\/li>\n<\/ul>\n<\/div>\n<div class=\"toggle-content__label-placeholder toggle-content__label-btn-height\" data-v-dfbf3dcb=\"\"><button class=\"c-button c-button--medium c-button--text c-button--text-standard toggle-content__button\" type=\"button\" data-v-dfbf3dcb=\"\" aria-label=\"\"><span class=\"c-button__text\"><span class=\"text-atom text-atom--body-strong text-atom--text-medium-sm\" data-v-ebc78423=\"\" data-v-04fa1704=\"\" data-test-id=\"expanded-button-text\"><span class=\"\" data-v-ebc78423=\"\">See less<\/span><\/span><\/span><\/button><\/div>\n<\/section>\n<\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"featured_media":24054,"template":"","meta":{"_acf_changed":false,"iawp_total_views":14},"tags":[],"class_list":["post-24077","activity","type-activity","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/activity\/24077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/activity"}],"about":[{"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/types\/activity"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/media\/24054"}],"wp:attachment":[{"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/media?parent=24077"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/tags?post=24077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}