{"id":23644,"date":"2025-01-20T15:31:11","date_gmt":"2025-01-20T15:31:11","guid":{"rendered":"https:\/\/welcomealghero.com\/?post_type=cafe&amp;p=23644"},"modified":"2025-01-20T15:31:11","modified_gmt":"2025-01-20T15:31:11","slug":"gelateria-k2","status":"publish","type":"cafe","link":"https:\/\/welcomealghero.com\/it\/cafe\/gelateria-k2\/","title":{"rendered":"Gelateria K2"},"content":{"rendered":"<p><span class=\"wordai-block rewrite-block enable-highlight\" data-id=\"1\">La Gelateria K2, in Via Roma, 73 ad Alghero, \u00e8 conosciuta come il posto dove andare per un delizioso gelato italiano.<\/span>\u00a0<span class=\"wordai-block rewrite-block enable-highlight\" data-id=\"2\">Questo premiato produttore di gelato offre molti gusti, tra cui il consigliatissimo Pistacchio.<\/span>\u00a0<span class=\"wordai-block rewrite-block enable-highlight\" data-id=\"3\">Il gelato \u00e8 delizioso e sono disponibili opzioni senza glutine per le persone con esigenze dietetiche particolari.<\/span>\u00a0<span class=\"wordai-block rewrite-block enable-highlight\" data-id=\"4\">La Gelateria K2 si rivolge anche ai vegani, agli intolleranti al lattosio e a chi ha restrizioni alimentari, offrendo gusti di soia.<\/span><\/p>\n<h3><span class=\"wordai-block rewrite-block enable-highlight\" data-id=\"5\">In evidenza...<\/span><\/h3>\n<ul>\n<li><span class=\"wordai-block rewrite-block enable-highlight\" data-id=\"7\">Un'ampia variet\u00e0 di gusti, comprese le alternative vegane<\/span><\/li>\n<li><span class=\"wordai-block rewrite-block enable-highlight\" data-id=\"9\">Gustate porzioni generose di ingredienti di alta qualit\u00e0<\/span><\/li>\n<li><span class=\"wordai-block rewrite-block enable-highlight\" data-id=\"11\">Servizio cordiale e flessibile alle esigenze dietetiche<\/span><\/li>\n<\/ul>","protected":false},"featured_media":23645,"template":"","meta":{"_acf_changed":false,"iawp_total_views":11},"cafe-tag":[8],"class_list":["post-23644","cafe","type-cafe","status-publish","has-post-thumbnail","hentry","cafe-tag-ice_cream"],"acf":[],"_links":{"self":[{"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/cafe\/23644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/cafe"}],"about":[{"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/types\/cafe"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/media\/23645"}],"wp:attachment":[{"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/media?parent=23644"}],"wp:term":[{"taxonomy":"cafe-tag","embeddable":true,"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/cafe-tag?post=23644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}