{"id":22984,"date":"2025-01-13T15:08:49","date_gmt":"2025-01-13T15:08:49","guid":{"rendered":"https:\/\/welcomealghero.com\/?post_type=hotels&amp;p=22984"},"modified":"2025-01-13T15:08:49","modified_gmt":"2025-01-13T15:08:49","slug":"la-meta-sporting-rooms","status":"publish","type":"hotels","link":"https:\/\/welcomealghero.com\/it\/hotels\/la-meta-sporting-rooms\/","title":{"rendered":"Sale sportive La Meta"},"content":{"rendered":"<h1 class=\"KOaa-hotel-name\">Sale sportive La Meta<\/h1>\n<div class=\"nWFW-address\">Via 1\u00b0 Maggio, 07041 Alghero, Sardegna, Italia<\/div>\n<div>\n<p><span class=\"wordai-block rewrite-block enable-highlight\" data-id=\"1\">Il Meta sporting rooms si trova nell'impianto di rugby Maria Pia. Dispone di 16 camere.<\/span><\/p>\n<p><span class=\"wordai-block rewrite-block enable-highlight\" data-id=\"2\">Le camere doppie e triple sono dotate di WiFi, aria condizionata, mini-frigo, bagno in camera e ingresso indipendente da entrambi i lati.<\/span><\/p>\n<p><span class=\"wordai-block rewrite-block enable-highlight\" data-id=\"3\">Ogni camera \u00e8 dotata di un'area esterna separata arredata con uno spazio per sedersi.<\/span><\/p>\n<p><span class=\"wordai-block rewrite-block enable-highlight\" data-id=\"4\">La palestra e il campo saranno a disposizione degli ospiti negli orari in cui non si gioca a rugby.<\/span><\/p>\n<p><span class=\"wordai-block rewrite-block enable-highlight\" data-id=\"5\">Il parcheggio si trova nell'impianto sportivo e, se disponibile, \u00e8 gratuito.<\/span><\/p>\n<p><span class=\"wordai-block rewrite-block enable-highlight\" data-id=\"6\">\u00c8 una destinazione ideale per i viaggiatori che vogliono essere vicini all'oceano.<\/span><\/p>\n<\/div>\n<div class=\"hotel_checklist\">\n<section id=\"\" class=\"Vdvb Vdvb-mod-size-desktop-large-mobile-standard Vdvb-mod-separator Vdvb-mod-color-default\">\n<div class=\"Vdvb-header-container\" data-testid=\"header\">\n<h2 class=\"Vdvb-title\">Servizi a La Meta Alghero Rugby<\/h2>\n<\/div>\n<ul class=\"kml-row\">\n<li class=\"kml-col-12-12 kml-col-6-12-m\"><span class=\"t8Xi-amenity-name\">Centro fitness<\/span><\/li>\n<li class=\"kml-col-12-12 kml-col-6-12-m\"><span class=\"t8Xi-amenity-name\">Bar\/Lounge<\/span><\/li>\n<li class=\"kml-col-12-12 kml-col-6-12-m\"><span class=\"t8Xi-amenity-name\">Wi-Fi gratuito<\/span><\/li>\n<li class=\"kml-col-12-12 kml-col-6-12-m\"><span class=\"t8Xi-amenity-name\">TV a schermo piatto<\/span><\/li>\n<li class=\"kml-col-12-12 kml-col-6-12-m\"><span class=\"t8Xi-amenity-name\">Articoli da bagno gratuiti<\/span><\/li>\n<li class=\"kml-col-12-12 kml-col-6-12-m\"><span class=\"t8Xi-amenity-name\">Navetta per l'aeroporto<\/span><\/li>\n<li class=\"kml-col-12-12 kml-col-6-12-m\"><span class=\"t8Xi-amenity-name\">Parcheggio<\/span><\/li>\n<li class=\"kml-col-12-12 kml-col-6-12-m\"><span class=\"t8Xi-amenity-name\">Animali ammessi su richiesta. Potrebbero essere applicate delle tariffe.<\/span><\/li>\n<li class=\"kml-col-12-12 kml-col-6-12-m\"><span class=\"t8Xi-amenity-name\">Asciugacapelli<\/span><\/li>\n<li class=\"kml-col-12-12 kml-col-6-12-m\"><span class=\"t8Xi-amenity-name\">Check-out rapido<\/span><\/li>\n<\/ul>\n<div>\n<div class=\"kml-row DbSA-categories-container\">\n<div class=\"kml-col-12-12 kml-col-6-12-m\">\n<p class=\"BxLB-category-name\">Nozioni di base<\/p>\n<ul>\n<li class=\"BxLB-amenity\"><span class=\"BxLB-amenity-name\">Wi-Fi gratuito<\/span><\/li>\n<li class=\"BxLB-amenity\"><span class=\"BxLB-amenity-name\">Aria condizionata<\/span><\/li>\n<li class=\"BxLB-amenity\"><span class=\"BxLB-amenity-name\">Articoli da bagno gratuiti<\/span><\/li>\n<\/ul>\n<\/div>\n<div class=\"kml-col-12-12 kml-col-6-12-m\">\n<p class=\"BxLB-category-name\">Parcheggio e trasporto<\/p>\n<ul>\n<li class=\"BxLB-amenity\"><span class=\"BxLB-amenity-name\">Navetta per l'aeroporto<\/span><\/li>\n<li class=\"BxLB-amenity\"><span class=\"BxLB-amenity-name\">Parcheggio<\/span><\/li>\n<\/ul>\n<\/div>\n<div class=\"kml-col-12-12 kml-col-6-12-m\">\n<p class=\"BxLB-category-name\">Pranzo<\/p>\n<ul>\n<li class=\"BxLB-amenity\"><span class=\"BxLB-amenity-name\">Bar\/Lounge<\/span><\/li>\n<li class=\"BxLB-amenity\"><span class=\"BxLB-amenity-name\">Minibar<\/span><\/li>\n<\/ul>\n<\/div>\n<div class=\"kml-col-12-12 kml-col-6-12-m\">\n<p class=\"BxLB-category-name\">Media e intrattenimento<\/p>\n<ul>\n<li class=\"BxLB-amenity\"><span class=\"BxLB-amenity-name\">TV a schermo piatto<\/span><\/li>\n<\/ul>\n<\/div>\n<div class=\"kml-col-12-12 kml-col-6-12-m\">\n<p class=\"BxLB-category-name\">Accessibilit\u00e0 e idoneit\u00e0<\/p>\n<ul>\n<li class=\"BxLB-amenity\"><span class=\"BxLB-amenity-name\">Animali ammessi su richiesta. Potrebbero essere applicate delle tariffe.<\/span><\/li>\n<\/ul>\n<\/div>\n<div class=\"kml-col-12-12 kml-col-6-12-m\">\n<p class=\"BxLB-category-name\">Bagno<\/p>\n<ul>\n<li class=\"BxLB-amenity\"><span class=\"BxLB-amenity-name\">Asciugacapelli<\/span><\/li>\n<\/ul>\n<\/div>\n<div class=\"kml-col-12-12 kml-col-6-12-m\">\n<p class=\"BxLB-category-name\">All'aperto<\/p>\n<ul>\n<li class=\"BxLB-amenity\"><span class=\"BxLB-amenity-name\">Giardino<\/span><\/li>\n<\/ul>\n<\/div>\n<div class=\"kml-col-12-12 kml-col-6-12-m\">\n<p class=\"BxLB-category-name\">Spazio di lavoro<\/p>\n<ul>\n<li class=\"BxLB-amenity\"><span class=\"BxLB-amenity-name\">Scrivania<\/span><\/li>\n<\/ul>\n<\/div>\n<div class=\"kml-col-12-12 kml-col-6-12-m\">\n<p class=\"BxLB-category-name\">Cose da fare<\/p>\n<ul>\n<li class=\"BxLB-amenity\"><span class=\"BxLB-amenity-name\">Accesso alla spiaggia<\/span><\/li>\n<\/ul>\n<\/div>\n<div class=\"kml-col-12-12 kml-col-6-12-m\">\n<p class=\"BxLB-category-name\">Generale<\/p>\n<ul>\n<li class=\"BxLB-amenity\"><span class=\"BxLB-amenity-name\">Disponibilit\u00e0 di stoccaggio<\/span><\/li>\n<\/ul>\n<\/div>\n<div class=\"kml-col-12-12 kml-col-6-12-m\">\n<p class=\"BxLB-category-name\">Salute e sicurezza<\/p>\n<ul>\n<li class=\"BxLB-amenity\"><span class=\"BxLB-amenity-name\">Pulizia giornaliera della casa<\/span><\/li>\n<\/ul>\n<\/div>\n<div class=\"kml-col-12-12 kml-col-6-12-m\">\n<p class=\"BxLB-category-name\">Servizi e comodit\u00e0<\/p>\n<ul>\n<li class=\"BxLB-amenity\"><span class=\"BxLB-amenity-name\">Check-out rapido<\/span><\/li>\n<\/ul>\n<\/div>\n<div class=\"kml-col-12-12 kml-col-6-12-m\">\n<p class=\"BxLB-category-name\">Fitness<\/p>\n<ul>\n<li class=\"BxLB-amenity\"><span class=\"BxLB-amenity-name\">Centro fitness<\/span><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<div class=\"DbSA-button-wrapper\">\n<p>&nbsp;<\/p>\n<div class=\"Iqt3-button-container\">\n<div class=\"Iqt3-button-content\"><span class=\"DbSA-link\">Mostra tutti i 17 servizi<\/span><\/div>\n<\/div>\n<div class=\"Iqt3-button-focus-outline\"><\/div>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<section id=\"\" class=\"Vdvb Vdvb-mod-size-desktop-large-mobile-standard Vdvb-mod-separator Vdvb-mod-color-default\">\n<div class=\"Vdvb-header-container\" data-testid=\"header\">\n<h2 class=\"Vdvb-title\">Politiche<\/h2>\n<\/div>\n<table class=\"Q6C3-table\">\n<tbody class=\"kml-row\">\n<tr class=\"kml-col-6-12-m\">\n<th class=\"Q6C3-title-wrapper\">\n<h3 class=\"Q6C3-title\">Check-in\/Check-out<\/h3>\n<\/th>\n<td class=\"Q6C3-description\">Check-in in qualsiasi momento dopo le 16:00, check-out in qualsiasi momento prima delle 11:00.<\/td>\n<\/tr>\n<tr class=\"kml-col-6-12-m\">\n<th class=\"Q6C3-title-wrapper\">\n<h3 class=\"Q6C3-title\">Cancellazione\/pagamento<\/h3>\n<\/th>\n<td class=\"Q6C3-description\">Le politiche di cancellazione\/pagamento variano a seconda del tipo di camera e del fornitore.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/section>","protected":false},"featured_media":22985,"template":"","meta":{"_acf_changed":false,"iawp_total_views":10},"hotel-tag":[],"class_list":["post-22984","hotels","type-hotels","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/hotels\/22984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/hotels"}],"about":[{"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/types\/hotels"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/media\/22985"}],"wp:attachment":[{"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/media?parent=22984"}],"wp:term":[{"taxonomy":"hotel-tag","embeddable":true,"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/hotel-tag?post=22984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}