{"id":23268,"date":"2025-01-11T11:56:30","date_gmt":"2025-01-11T11:56:30","guid":{"rendered":"https:\/\/welcomealghero.com\/restaurant\/ristorante-gioberti\/"},"modified":"2025-01-11T11:56:30","modified_gmt":"2025-01-11T11:56:30","slug":"ristorante-gioberti","status":"publish","type":"restaurant","link":"https:\/\/welcomealghero.com\/it\/restaurant\/ristorante-gioberti\/","title":{"rendered":"Ristorante Gioberti"},"content":{"rendered":"<p>&nbsp;<\/p>\n<div>\n<h2 class=\"font-weight-bold mb-3 line-height-1 color-primary-darkest\">Circa<\/h2>\n<p>Ristorante di Pesce Gioberti ~ Il ristorante ha un'atmosfera rilassata e un ambiente antico. Il menu offre specialit\u00e0 di pesce, come salumi e pasta ai gamberi. Prenotate in anticipo perch\u00e9 la fila pu\u00f2 essere lunga. La parte migliore del Ristorante di Pesce Gioberti \u00e8 la pasta ai frutti di mare!<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<div class=\"flex rounded-16 p-4 bg-indigo-lightest\">\n<h4 class=\"font-weight-bold pb-2\" style=\"color: #2c365d;\">Perch\u00e9 dovresti andare...<\/h4>\n<div><\/div>\n<ul>\n<li class=\"d-flex align-items-center\">Gustate cibi deliziosi come la pasta ai frutti di mare dal sapore umami e i salumi.<\/li>\n<li class=\"d-flex align-items-center\">Godetevi il servizio attento del nostro personale<\/li>\n<li class=\"d-flex align-items-center\">Gustate piatti unici come il risotto alle pere o la fregola Sarda<\/li>\n<\/ul>\n<\/div>\n<p>Via Gioberti, 40, 07041 Alghero SS, Italia<br \/>\n<a href=\"https:\/\/www.giobertialghero.it\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.giobertialghero.it\/<\/a><br \/>\n+39 079 492 2406<\/p>","protected":false},"featured_media":23309,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"iawp_total_views":2},"restaurant-tag":[],"class_list":["post-23268","restaurant","type-restaurant","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/restaurant\/23268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/restaurant"}],"about":[{"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/types\/restaurant"}],"replies":[{"embeddable":true,"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/comments?post=23268"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/media\/23309"}],"wp:attachment":[{"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/media?parent=23268"}],"wp:term":[{"taxonomy":"restaurant-tag","embeddable":true,"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/restaurant-tag?post=23268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}