{"id":23269,"date":"2025-01-11T13:03:16","date_gmt":"2025-01-11T13:03:16","guid":{"rendered":"https:\/\/welcomealghero.com\/restaurant\/ristorante-sa-mesa\/"},"modified":"2025-01-11T13:03:16","modified_gmt":"2025-01-11T13:03:16","slug":"ristorante-sa-mesa","status":"publish","type":"restaurant","link":"https:\/\/welcomealghero.com\/it\/restaurant\/ristorante-sa-mesa\/","title":{"rendered":"Ristorante Sa Mesa"},"content":{"rendered":"<p>&nbsp;<\/p>\n<div>\n<h2 class=\"font-weight-bold mb-3 line-height-1 color-primary-darkest\">Circa<\/h2>\n<p>Ristorante Sa Mesa ~ Il ristorante si trova in una bella strada e vanta un arredamento autentico e di buon gusto. Il ristorante ha un arredamento autentico e di buon gusto ed \u00e8 situato in una bella strada. Gli ospiti del ristorante lodano il cibo preparato con ingredienti freschi e locali. Inoltre, lodano il personale per la sua cordialit\u00e0 e attenzione. Alcuni consigliano di prenotare, soprattutto per i posti all'aperto.<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<div class=\"flex rounded-16 p-4 bg-indigo-lightest\">\n<h4 class=\"font-weight-bold pb-2\" style=\"color: #2c365d;\">Perch\u00e9 dovresti andare...<\/h4>\n<div><\/div>\n<ul>\n<li class=\"d-flex align-items-center\">Assaporate l'autentica cucina sarda con piatti come la fregula o la crema catalana.<\/li>\n<li class=\"d-flex align-items-center\">Potrete gustare porzioni generose di cibi deliziosi a prezzi equi<\/li>\n<li class=\"d-flex align-items-center\">Potrete godere di un'atmosfera calda sia all'interno che all'esterno, con un servizio clienti impeccabile.<\/li>\n<\/ul>\n<\/div>\n<p>Via Principe Umberto, 57, 07041 Alghero SS, Italia<br \/>\n<a href=\"http:\/\/www.ristorantesamesa.eu\/\" target=\"_blank\" rel=\"noopener\">http:\/\/www.ristorantesamesa.eu\/<\/a><br \/>\n+39 079 412 4813<\/p>","protected":false},"featured_media":23270,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"iawp_total_views":3},"restaurant-tag":[],"class_list":["post-23269","restaurant","type-restaurant","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/restaurant\/23269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/restaurant"}],"about":[{"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/types\/restaurant"}],"replies":[{"embeddable":true,"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/comments?post=23269"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/media\/23270"}],"wp:attachment":[{"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/media?parent=23269"}],"wp:term":[{"taxonomy":"restaurant-tag","embeddable":true,"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/restaurant-tag?post=23269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}