{"id":23273,"date":"2025-01-11T16:32:27","date_gmt":"2025-01-11T16:32:27","guid":{"rendered":"https:\/\/welcomealghero.com\/restaurant\/ok-pizza-evolution-ristorante-pizzeria\/"},"modified":"2025-01-11T16:32:27","modified_gmt":"2025-01-11T16:32:27","slug":"ok-pizza-evolution-ristorante-pizzeria","status":"publish","type":"restaurant","link":"https:\/\/welcomealghero.com\/it\/restaurant\/ok-pizza-evolution-ristorante-pizzeria\/","title":{"rendered":"Ok Pizza Evolution - Ristorante Pizzeria"},"content":{"rendered":"<p>&nbsp;<\/p>\n<div>\n<h2 class=\"font-weight-bold mb-3 line-height-1 color-primary-darkest\">Circa<\/h2>\n<p>Ok Pizza Evolution ~ Questa pizzeria si trova ad Alghero in Sardegna e offre servizio d'asporto o di consegna. Il ristorante pu\u00f2 ospitare fino a 40 persone e offre il servizio al tavolo. Il ristorante accetta pagamenti con carta di credito e serve alcolici.<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<div class=\"flex rounded-16 p-4 bg-indigo-lightest\">\n<h4 class=\"font-weight-bold pb-2\" style=\"color: #2c365d;\">Perch\u00e9 dovresti andare...<\/h4>\n<div><\/div>\n<ul>\n<li class=\"d-flex align-items-center\">Godetevi le pizze gourmet dalla crosta croccante<\/li>\n<li class=\"d-flex align-items-center\">Sperimentate un servizio top-Top da parte di un personale cordiale<\/li>\n<li class=\"d-flex align-items-center\">Offerte come dessert gratuiti o presentazioni creative della pizza<\/li>\n<\/ul>\n<\/div>\n<p>Viale della Resistenza, 8, 07041 Alghero SS, Italia<br \/>\n<a href=\"https:\/\/www.okpizzaevolution.it\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.okpizzaevolution.it\/<\/a><br \/>\n+39 079 973 3022<\/p>","protected":false},"featured_media":23316,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"iawp_total_views":12},"restaurant-tag":[4],"class_list":["post-23273","restaurant","type-restaurant","status-publish","has-post-thumbnail","hentry","restaurant-tag-pizza"],"acf":[],"_links":{"self":[{"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/restaurant\/23273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/restaurant"}],"about":[{"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/types\/restaurant"}],"replies":[{"embeddable":true,"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/comments?post=23273"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/media\/23316"}],"wp:attachment":[{"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/media?parent=23273"}],"wp:term":[{"taxonomy":"restaurant-tag","embeddable":true,"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/restaurant-tag?post=23273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}