{"id":23274,"date":"2025-01-11T17:34:03","date_gmt":"2025-01-11T17:34:03","guid":{"rendered":"https:\/\/welcomealghero.com\/restaurant\/trattoria-cavour\/"},"modified":"2025-01-11T17:34:03","modified_gmt":"2025-01-11T17:34:03","slug":"trattoria-cavour","status":"publish","type":"restaurant","link":"https:\/\/welcomealghero.com\/it\/restaurant\/trattoria-cavour\/","title":{"rendered":"Trattoria Cavour"},"content":{"rendered":"<p>&nbsp;<\/p>\n<div>\n<h2 class=\"font-weight-bold mb-3 line-height-1 color-primary-darkest\">Circa<\/h2>\n<p>Trattoria Cavour ~ L'incantevole ristorante di Alghero offre una cucina casalinga a un prezzo ragionevole. Il personale \u00e8 laborioso e cordiale, ma \u00e8 meglio prenotare in anticipo. Il menu comprende piatti a base di ingredienti freschi di stagione, come le vongole pescate ieri e i funghi porcini.<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<div class=\"flex rounded-16 p-4 bg-indigo-lightest\">\n<h4 class=\"font-weight-bold pb-2\" style=\"color: #2c365d;\">Perch\u00e9 dovresti andare...<\/h4>\n<div><\/div>\n<ul>\n<li class=\"d-flex align-items-center\">Gustate l'autentico cibo sardo preparato con ingredienti di stagione<\/li>\n<li class=\"d-flex align-items-center\">Provate piatti come i Culurgiones ripieni di pur\u00e8 di patate o i Culurgiones ripieni di formaggio di pecora.<\/li>\n<li class=\"d-flex align-items-center\">Scoprite i grandi abbinamenti di vino per la pasta.<\/li>\n<\/ul>\n<\/div>\n<p>Via Camillo Benso Conte di Cavour, 110, 07041 Alghero SS, Italia<br \/>\n+39 079 412 3863<\/p>","protected":false},"featured_media":23318,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"iawp_total_views":19},"restaurant-tag":[],"class_list":["post-23274","restaurant","type-restaurant","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/restaurant\/23274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/restaurant"}],"about":[{"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/types\/restaurant"}],"replies":[{"embeddable":true,"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/comments?post=23274"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/media\/23318"}],"wp:attachment":[{"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/media?parent=23274"}],"wp:term":[{"taxonomy":"restaurant-tag","embeddable":true,"href":"https:\/\/welcomealghero.com\/it\/wp-json\/wp\/v2\/restaurant-tag?post=23274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}